{"id":41145,"date":"2025-02-14T15:03:18","date_gmt":"2025-02-14T15:03:18","guid":{"rendered":"https:\/\/www.fanzword.com\/?p=41145"},"modified":"2025-02-14T15:03:18","modified_gmt":"2025-02-14T15:03:18","slug":"ancelotti-revele-un-developpement-important-au-real-madrid-avant-le-sommet-de-city","status":"publish","type":"post","link":"https:\/\/www.fanzword.com\/fr\/ancelotti-revele-un-developpement-important-au-real-madrid-avant-le-sommet-de-city\/","title":{"rendered":"Ancelotti r\u00e9v\u00e8le un d\u00e9veloppement important au Real Madrid avant le sommet de City"},"content":{"rendered":"<p>L&rsquo;entra\u00eeneur du Real Madrid, Carlo Ancelotti, a r\u00e9v\u00e9l\u00e9 de bonnes nouvelles pour les fans du Real Madrid avant le prochain match contre Manchester City lors du match retour des huiti\u00e8mes de finale de la Ligue des champions.<\/p>\n<p>Le Real Madrid se pr\u00e9pare \u00e0 affronter Osasuna samedi en Liga, avant de recevoir City au Santiago Bernabeu mercredi prochain.<\/p>\n<p>Ancelotti a confirm\u00e9 que le trio Lucas Vazquez, Antonio Rudiger et David Alaba peuvent tous participer contre City.<\/p>\n<p>Le trio continuera d&rsquo;\u00eatre absent contre Osasuna, et l&rsquo;entra\u00eeneur italien a \u00e9galement confirm\u00e9 que Fede Valverde continuera de participer au poste d&rsquo;arri\u00e8re droit, et Aur\u00e9lien Tchouameni au poste de d\u00e9fenseur central.<\/p>\n<p>Ainsi, le Real jouera le prochain match contre City uniquement sans le duo souffrant de blessures aux ligaments crois\u00e9s, Eder Militao et Dani Carvajal.<\/p>\n<p>Le Real Madrid n&rsquo;a besoin que d&rsquo;un match nul ou d&rsquo;une victoire quel que soit le score pour se qualifier pour les huiti\u00e8mes de finale et affronter soit l&rsquo;Atl\u00e9tico Madrid, soit le Bayer Leverkusen.<\/p>\n<p>Le Real Madrid abordera le match contre Osasuna en t\u00eate du championnat espagnol, avec un point d&rsquo;avance sur l&rsquo;Atl\u00e9tico Madrid et deux points d&rsquo;avance sur Barcelone.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;entra\u00eeneur du Real Madrid, Carlo Ancelotti, a r\u00e9v\u00e9l\u00e9 de bonnes nouvelles pour les fans du Real Madrid avant le prochain match contre Manchester City lors du match retour des huiti\u00e8mes de finale de la Ligue des champions. Le Real Madrid se pr\u00e9pare \u00e0 affronter Osasuna samedi en Liga, avant de recevoir City au Santiago Bernabeu [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":41141,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfio_featured_image":false,"sfio_embed_code":"","footnotes":""},"categories":[10],"tags":[],"class_list":["post-41145","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee"],"_links":{"self":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/41145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/comments?post=41145"}],"version-history":[{"count":1,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/41145\/revisions"}],"predecessor-version":[{"id":41146,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/41145\/revisions\/41146"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/media\/41141"}],"wp:attachment":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/media?parent=41145"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/categories?post=41145"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/tags?post=41145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}