{"id":38744,"date":"2025-01-20T17:11:00","date_gmt":"2025-01-20T17:11:00","guid":{"rendered":"https:\/\/www.fanzword.com\/?p=38744"},"modified":"2025-01-20T17:11:00","modified_gmt":"2025-01-20T17:11:00","slug":"simeone-fait-taire-ancelotti-et-ceballos-pour-avoir-aide-les-arbitres-du-real-madrid","status":"publish","type":"post","link":"https:\/\/www.fanzword.com\/fr\/simeone-fait-taire-ancelotti-et-ceballos-pour-avoir-aide-les-arbitres-du-real-madrid\/","title":{"rendered":"Simeone fait taire Ancelotti et Ceballos pour avoir aid\u00e9 les arbitres du Real Madrid"},"content":{"rendered":"<p>L&rsquo;entra\u00eeneur de l&rsquo;Atl\u00e9tico Madrid, Diego Simeone, a continu\u00e9 d&rsquo;accuser le Real Madrid de tirer profit de l&rsquo;arbitrage, et a fait taire Carlo Ancelotti et Dani Ceballos apr\u00e8s leur r\u00e9cente r\u00e9ponse \u00e0 son \u00e9gard.<\/p>\n<p>L&rsquo;entra\u00eeneur argentin a d\u00e9clar\u00e9 plus t\u00f4t que regarder 100 ans de Real Madrid fait que les gens ne se demandent pas comment ils gagnent, faisant r\u00e9f\u00e9rence aux compliments de l&rsquo;arbitrage \u00e0 leur \u00e9gard.<\/p>\n<p>Ceballos a r\u00e9pondu \u00e0 Simeone en affirmant qu&rsquo;il disait cela parce qu&rsquo;il ne pouvait pas oublier les victoires du Real Madrid en Ligue des champions contre lui en 2014 et 2016, tandis qu&rsquo;Ancelotti a d\u00e9clar\u00e9 que ces affirmations \u00e9taient sans fondement.<\/p>\n<p>Simeone a \u00e9t\u00e9 \u00e0 nouveau interrog\u00e9 sur le sujet avant le match de Ligue des champions contre le Bayer Leverkusen, et il a r\u00e9pondu : \u00ab Je n&rsquo;aime pas parler de mes co\u00e9quipiers. \u00bb<\/p>\n<p>\u00ab\u00a0Mais je me souviens que quand Ancelotti \u00e9tait entra\u00eeneur du Bayern Munich, il parlait avec force de ce qui se passait sur le terrain face au Real Madrid\u00a0\u00bb, a-t-il ajout\u00e9.<\/p>\n<p>\u00ab\u00a0Je me souviens aussi des d\u00e9clarations de Ceballos quand il \u00e9tait joueur du Real Betis, ils jouent bien et le Real Madrid est une grande \u00e9quipe mais quand ils \u00e9taient dans une autre \u00e9quipe, leurs opinions \u00e9taient diff\u00e9rentes\u00a0\u00bb, a-t-il conclu.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;entra\u00eeneur de l&rsquo;Atl\u00e9tico Madrid, Diego Simeone, a continu\u00e9 d&rsquo;accuser le Real Madrid de tirer profit de l&rsquo;arbitrage, et a fait taire Carlo Ancelotti et Dani Ceballos apr\u00e8s leur r\u00e9cente r\u00e9ponse \u00e0 son \u00e9gard. L&rsquo;entra\u00eeneur argentin a d\u00e9clar\u00e9 plus t\u00f4t que regarder 100 ans de Real Madrid fait que les gens ne se demandent pas comment [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":38739,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfio_featured_image":false,"sfio_embed_code":"","footnotes":""},"categories":[10],"tags":[],"class_list":["post-38744","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee"],"_links":{"self":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/38744","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/comments?post=38744"}],"version-history":[{"count":1,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/38744\/revisions"}],"predecessor-version":[{"id":38745,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/38744\/revisions\/38745"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/media\/38739"}],"wp:attachment":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/media?parent=38744"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/categories?post=38744"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/tags?post=38744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}