{"id":38216,"date":"2025-01-15T11:45:47","date_gmt":"2025-01-15T11:45:47","guid":{"rendered":"https:\/\/www.fanzword.com\/?p=38216"},"modified":"2025-01-15T11:45:47","modified_gmt":"2025-01-15T11:45:47","slug":"le-salaire-astronomique-de-ronaldo-revele-dans-son-nouveau-contrat-avec-al-nassr","status":"publish","type":"post","link":"https:\/\/www.fanzword.com\/fr\/le-salaire-astronomique-de-ronaldo-revele-dans-son-nouveau-contrat-avec-al-nassr\/","title":{"rendered":"Le salaire astronomique de Ronaldo r\u00e9v\u00e9l\u00e9 dans son nouveau contrat avec Al-Nassr"},"content":{"rendered":"<p>Cristiano Ronaldo restera le joueur le mieux pay\u00e9 de l&rsquo;histoire du football lorsqu&rsquo;il renouvellera son contrat avec Al Nassr.<\/p>\n<p>Les m\u00e9dias saoudiens ont confirm\u00e9 que \u00ab Don \u00bb avait finalis\u00e9 son accord avec la direction d&rsquo;Al-Nasr pour renouveler pour une ann\u00e9e suppl\u00e9mentaire jusqu&rsquo;\u00e0 la Coupe du monde 2026.<\/p>\n<p>Le Daily Mail rapporte que Ronaldo recevra un salaire l\u00e9gendaire de 153 millions de livres sterling par an, soit environ 182 millions d&rsquo;euros.<\/p>\n<p>Al-Nassr paiera au joueur de 39 ans 3,8 millions d&rsquo;euros par semaine, ce qui signifie que la journ\u00e9e de Ronaldo vaut pr\u00e8s de 500 000 euros !<\/p>\n<p>Le salaire de Ronaldo ne se limite pas \u00e0 ce qui a \u00e9t\u00e9 mentionn\u00e9, mais il re\u00e7oit \u00e9galement d&rsquo;autres sommes \u00e9normes provenant de la promotion de l&rsquo;Arabie saoudite, qui atteindraient 50 millions d&rsquo;euros.<\/p>\n<p>De plus, le nouveau contrat permet \u00e0 Ronaldo d&rsquo;obtenir 5% des actions du club.<\/p>\n<p>Il est \u00e0 noter que Ronaldo, malgr\u00e9 son \u00e9norme salaire, n&rsquo;a remport\u00e9 aucun titre officiel avec Al-Nassr jusqu&rsquo;\u00e0 pr\u00e9sent, mais il a annonc\u00e9 que son objectif \u00e9tait de remporter la Ligue des champions de l&rsquo;AFC pour l&rsquo;\u00e9lite cette saison.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cristiano Ronaldo restera le joueur le mieux pay\u00e9 de l&rsquo;histoire du football lorsqu&rsquo;il renouvellera son contrat avec Al Nassr. Les m\u00e9dias saoudiens ont confirm\u00e9 que \u00ab Don \u00bb avait finalis\u00e9 son accord avec la direction d&rsquo;Al-Nasr pour renouveler pour une ann\u00e9e suppl\u00e9mentaire jusqu&rsquo;\u00e0 la Coupe du monde 2026. Le Daily Mail rapporte que Ronaldo recevra [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":38210,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfio_featured_image":false,"sfio_embed_code":"","footnotes":""},"categories":[10],"tags":[],"class_list":["post-38216","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee"],"_links":{"self":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/38216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/comments?post=38216"}],"version-history":[{"count":1,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/38216\/revisions"}],"predecessor-version":[{"id":38217,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/38216\/revisions\/38217"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/media\/38210"}],"wp:attachment":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/media?parent=38216"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/categories?post=38216"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/tags?post=38216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}