{"id":37082,"date":"2025-01-05T11:15:26","date_gmt":"2025-01-05T11:15:26","guid":{"rendered":"https:\/\/www.fanzword.com\/?p=37082"},"modified":"2025-01-05T11:15:26","modified_gmt":"2025-01-05T11:15:26","slug":"pourquoi-messi-a-t-il-ete-absent-de-la-ceremonie-dhonneur-du-president-americain-biden","status":"publish","type":"post","link":"https:\/\/www.fanzword.com\/fr\/pourquoi-messi-a-t-il-ete-absent-de-la-ceremonie-dhonneur-du-president-americain-biden\/","title":{"rendered":"Pourquoi Messi a-t-il \u00e9t\u00e9 absent de la c\u00e9r\u00e9monie d&rsquo;honneur du pr\u00e9sident am\u00e9ricain Biden ?"},"content":{"rendered":"<p>Lionel Messi n&rsquo;a pas particip\u00e9 \u00e0 la c\u00e9r\u00e9monie honorant 19 personnes par le pr\u00e9sident am\u00e9ricain Joe Biden \u00e0 la Maison Blanche, qui a eu lieu samedi.<\/p>\n<p>L&rsquo;international argentin a re\u00e7u de Biden la M\u00e9daille pr\u00e9sidentielle de la libert\u00e9, la plus haute distinction civile aux \u00c9tats-Unis, d\u00e9cern\u00e9e pour des r\u00e9alisations dans des domaines caritatifs et institutionnels ayant un impact significatif.<\/p>\n<p>L&rsquo;absence de Messi \u00e0 la c\u00e9r\u00e9monie, qui comprenait des noms c\u00e9l\u00e8bres comme l&rsquo;acteur Denzel Washington, a soulev\u00e9 de nombreuses questions et sp\u00e9culations sur le r\u00f4le \u00e9ventuel de positions politiques dans cette d\u00e9cision.<\/p>\n<p>De son c\u00f4t\u00e9, Messi a mis fin \u00e0 toute cette controverse en publiant une d\u00e9claration via son \u00e9quipe m\u00e9diatique \u00e0 la presse am\u00e9ricaine, s&rsquo;excusant pour son absence et r\u00e9v\u00e9lant la raison inattendue de celle-ci.<\/p>\n<p>L&rsquo;\u00e9quipe de Messi a d\u00e9clar\u00e9 : \u00ab\u00a0Messi se sent extr\u00eamement fier et honor\u00e9 par cette reconnaissance.\u00a0\u00bb<\/p>\n<p>Elle a ajout\u00e9 : \u00ab\u00a0Messi n&rsquo;a pas pu assister en raison de conflits d&#8217;emploi du temps et d&rsquo;engagements pr\u00e9vus \u00e0 l&rsquo;avance, mais il esp\u00e8re avoir l&rsquo;occasion de rencontrer le pr\u00e9sident Biden dans un avenir proche.\u00a0\u00bb<\/p>\n<p>Messi a rejoint l&rsquo;Inter Miami \u00e0 l&rsquo;\u00e9t\u00e9 2023, et depuis, il est devenu l&rsquo;une des figures les plus influentes de la soci\u00e9t\u00e9 am\u00e9ricaine.<\/p>\n<p>Le joueur de 36 ans se pr\u00e9pare \u00e0 mener son \u00e9quipe dans un \u00e9v\u00e9nement majeur, la Coupe du monde des clubs 2025, pr\u00e9vue en juin prochain sur le sol am\u00e9ricain.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lionel Messi n&rsquo;a pas particip\u00e9 \u00e0 la c\u00e9r\u00e9monie honorant 19 personnes par le pr\u00e9sident am\u00e9ricain Joe Biden \u00e0 la Maison Blanche, qui a eu lieu samedi. L&rsquo;international argentin a re\u00e7u de Biden la M\u00e9daille pr\u00e9sidentielle de la libert\u00e9, la plus haute distinction civile aux \u00c9tats-Unis, d\u00e9cern\u00e9e pour des r\u00e9alisations dans des domaines caritatifs et institutionnels [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":37078,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfio_featured_image":false,"sfio_embed_code":"","footnotes":""},"categories":[10],"tags":[],"class_list":["post-37082","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee"],"_links":{"self":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/37082","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/comments?post=37082"}],"version-history":[{"count":1,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/37082\/revisions"}],"predecessor-version":[{"id":37083,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/37082\/revisions\/37083"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/media\/37078"}],"wp:attachment":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/media?parent=37082"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/categories?post=37082"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/tags?post=37082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}