{"id":36594,"date":"2025-01-01T10:47:55","date_gmt":"2025-01-01T10:47:55","guid":{"rendered":"https:\/\/www.fanzword.com\/?p=36594"},"modified":"2025-01-01T10:47:55","modified_gmt":"2025-01-01T10:47:55","slug":"un-joueur-saoudien-se-retire-du-football-international-apres-la-deception-de-la-coupe-du-golfe","status":"publish","type":"post","link":"https:\/\/www.fanzword.com\/fr\/un-joueur-saoudien-se-retire-du-football-international-apres-la-deception-de-la-coupe-du-golfe\/","title":{"rendered":"Un joueur saoudien se retire du football international apr\u00e8s la d\u00e9ception de la Coupe du Golfe"},"content":{"rendered":"<p>Les m\u00e9dias saoudiens ont r\u00e9v\u00e9l\u00e9 qu&rsquo;un joueur saoudien avait d\u00e9cid\u00e9 de prendre sa retraite internationale apr\u00e8s que l&rsquo;\u00e9quipe saoudienne ait fait ses adieux \u00e0 la Coupe du Golfe en demi-finale.<\/p>\n<p>Malgr\u00e9 une bonne performance en phase de groupes, \u00ab\u00a0Al-Akhdar\u00a0\u00bb n&rsquo;a pas r\u00e9ussi \u00e0 vaincre Oman en demi-finale et a perdu 2-1, ce qui a d\u00e9clench\u00e9 de vives critiques \u00e0 l&rsquo;encontre des joueurs et de l&rsquo;entra\u00eeneur Herv\u00e9 Renard.<\/p>\n<p>Selon les derni\u00e8res informations, le gardien Mohammed Al Owais a inform\u00e9 les responsables de l&rsquo;\u00e9quipe nationale saoudienne qu&rsquo;il avait pris sa retraite internationale et qu&rsquo;il ne porterait plus le maillot vert.<\/p>\n<p>Le gardien d&rsquo;Al Hilal a un long palmar\u00e8s avec l&rsquo;Arabie Saoudite, puisqu&rsquo;il a repr\u00e9sent\u00e9 son pays lors de 53 matches internationaux et a \u00e9t\u00e9 sans aucun doute l&rsquo;une des stars les plus importantes de la Coupe du monde 2022 et de la victoire contre l&rsquo;Argentine au premier tour des groupes.<\/p>\n<p>A 33 ans, et \u00e0 la lumi\u00e8re de la campagne de remplacement et de renouvellement men\u00e9e par Renard, Al Owais a consid\u00e9r\u00e9 que c&rsquo;\u00e9tait le bon moment pour quitter l&rsquo;\u00e9quipe nationale et donner l&rsquo;opportunit\u00e9 \u00e0 davantage de jeunes joueurs.<\/p>\n<p>De cette fa\u00e7on, il est fort probable que le gardien Ahmed Al-Kassar ou Nawaf Al-Aqidi seront l&rsquo;un d&rsquo;entre eux qui gardera le but de l&rsquo;\u00e9quipe nationale saoudienne en mars prochain lors des \u00e9liminatoires de la Coupe du monde 2026.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les m\u00e9dias saoudiens ont r\u00e9v\u00e9l\u00e9 qu&rsquo;un joueur saoudien avait d\u00e9cid\u00e9 de prendre sa retraite internationale apr\u00e8s que l&rsquo;\u00e9quipe saoudienne ait fait ses adieux \u00e0 la Coupe du Golfe en demi-finale. Malgr\u00e9 une bonne performance en phase de groupes, \u00ab\u00a0Al-Akhdar\u00a0\u00bb n&rsquo;a pas r\u00e9ussi \u00e0 vaincre Oman en demi-finale et a perdu 2-1, ce qui a d\u00e9clench\u00e9 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":36590,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfio_featured_image":false,"sfio_embed_code":"","footnotes":""},"categories":[10],"tags":[],"class_list":["post-36594","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee"],"_links":{"self":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/36594","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/comments?post=36594"}],"version-history":[{"count":1,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/36594\/revisions"}],"predecessor-version":[{"id":36595,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/36594\/revisions\/36595"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/media\/36590"}],"wp:attachment":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/media?parent=36594"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/categories?post=36594"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/tags?post=36594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}