{"id":34261,"date":"2024-12-07T13:35:12","date_gmt":"2024-12-07T13:35:12","guid":{"rendered":"https:\/\/www.fanzword.com\/?p=34261"},"modified":"2024-12-07T13:35:12","modified_gmt":"2024-12-07T13:35:12","slug":"dates-des-matchs-des-equipes-arabes-a-la-coupe-du-monde-des-clubs-2025","status":"publish","type":"post","link":"https:\/\/www.fanzword.com\/fr\/dates-des-matchs-des-equipes-arabes-a-la-coupe-du-monde-des-clubs-2025\/","title":{"rendered":"Dates des matchs des \u00e9quipes arabes \u00e0 la Coupe du Monde des Clubs 2025"},"content":{"rendered":"<p>La FIFA a annonc\u00e9 le calendrier des matches de la phase de groupes de la Coupe du Monde des Clubs de la FIFA 2025, qui se d\u00e9roulera aux \u00c9tats-Unis d&rsquo;Am\u00e9rique.<\/p>\n<p>Le tirage au sort du tournoi a eu lieu jeudi dernier \u00e0 Miami et a donn\u00e9 lieu \u00e0 de nombreuses confrontations enflamm\u00e9es, notamment entre \u00e9quipes arabes.<\/p>\n<p>L&rsquo;\u00c9gyptien Al-Ahly disputera le match d&rsquo;ouverture contre l&rsquo;Inter Miami, dirig\u00e9 par Lionel Messi, et sa date a \u00e9t\u00e9 modifi\u00e9e au 14 juin au lieu du 15 juin.<\/p>\n<p>Les supporters attendent qu&rsquo;Al Hilal Arabie Saoudite affronte le Real Madrid, tandis que le Wydad fait face \u00e0 une t\u00e2che difficile contre Manchester City et la Juventus, tandis que l&rsquo;Esp\u00e9rance tunisienne entre dans le groupe de Chelsea.<\/p>\n<p>Nous passons en revue ci-dessous avec vous le calendrier des matchs des \u00e9quipes arabes lors de la Coupe du Monde des Clubs 2025.<\/p>\n<h2>Dates des matchs d\u2019Al-Ahly lors de la Coupe du monde des clubs 2025<\/h2>\n<p>Al-Ahly x Inter Miami \u2013 14 juin 2024 (4h00, heure du Caire)<br \/>\nAl-Ahly x Palmeiras &#8211; jeudi 19 juin 2025 (20h00, heure du Caire)<br \/>\nAl-Ahly x Porto \u2013 24 juin 2025 (5h00, heure du Caire)<\/p>\n<h2>Dates des matchs d\u2019Al Hilal lors de la Coupe du Monde des Clubs 2025<\/h2>\n<p>Al Hilal x Real Madrid &#8211; 18 juin 2025 (13h00, heure de La Mecque)<br \/>\nAl Hilal x Salzbourg \u2013 22 juin 2025 (6h00, heure de La Mecque)<br \/>\nAl Hilal x Pachuca \u2013 26 juin 2025 (7h00, heure de La Mecque)<\/p>\n<h2>Dates des matchs de l&rsquo;Esp\u00e9rance lors du Mondial des Clubs 2025<\/h2>\n<p>Esp\u00e9rance x Flamengo &#8211; 16 juin 2025 (5h00, heure de Tunisie)<br \/>\nEsp\u00e9rance x Lyon &#8211; 21 juin 2025 (2h00 heure de Tunisie)<br \/>\nEsp\u00e9rance x Chelsea &#8211; 24 juin 2025 (5h00 heure de Tunisie)<\/p>\n<h2>Dates des matchs du Wydad au Mondial des Clubs 2025<\/h2>\n<p>Wydad x Manchester City &#8211; 18 juin 2025 (20h00, heure du Maroc)<br \/>\nWydad x Juventus &#8211; 22 juin 2025 (20h00, heure du Maroc)<br \/>\nWydad x Al Ain \u2013 26 juin 2025 (11h00, heure du Maroc)<\/p>\n<h2>Matchs d&rsquo;Al A\u00efn lors de la Coupe du Monde des Clubs 2025<\/h2>\n<p>Al Ain x Juventus \u2013 18 juin 2025 (8h00, heure des \u00c9mirats arabes unis)<br \/>\nAl Ain x Manchester City \u2013 22 juin 2025 (7h00, heure des \u00c9mirats arabes unis)<br \/>\nAl Ain x Wydad \u2013 26 juin 2025 (14h00, heure des \u00c9mirats arabes unis)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La FIFA a annonc\u00e9 le calendrier des matches de la phase de groupes de la Coupe du Monde des Clubs de la FIFA 2025, qui se d\u00e9roulera aux \u00c9tats-Unis d&rsquo;Am\u00e9rique. Le tirage au sort du tournoi a eu lieu jeudi dernier \u00e0 Miami et a donn\u00e9 lieu \u00e0 de nombreuses confrontations enflamm\u00e9es, notamment entre \u00e9quipes [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":34204,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfio_featured_image":false,"sfio_embed_code":"","footnotes":""},"categories":[10],"tags":[],"class_list":["post-34261","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee"],"_links":{"self":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/34261","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/comments?post=34261"}],"version-history":[{"count":1,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/34261\/revisions"}],"predecessor-version":[{"id":34262,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/34261\/revisions\/34262"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/media\/34204"}],"wp:attachment":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/media?parent=34261"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/categories?post=34261"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/tags?post=34261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}