{"id":33229,"date":"2024-11-27T22:00:48","date_gmt":"2024-11-27T22:00:48","guid":{"rendered":"https:\/\/www.fanzword.com\/?p=33229"},"modified":"2024-11-27T22:00:48","modified_gmt":"2024-11-27T22:00:48","slug":"liverpool-remporte-une-victoire-bien-meritee-contre-le-real-madrid-video","status":"publish","type":"post","link":"https:\/\/www.fanzword.com\/fr\/liverpool-remporte-une-victoire-bien-meritee-contre-le-real-madrid-video\/","title":{"rendered":"Liverpool remporte une victoire bien m\u00e9rit\u00e9e contre le Real Madrid (vid\u00e9o)"},"content":{"rendered":"<p>Liverpool a mis fin au n\u0153ud du Real Madrid en remportant finalement la victoire contre le Royal Club, sur le score de 2-0, au cinqui\u00e8me tour de la Ligue des Champions.<\/p>\n<p>Les Reds ont pris l&rsquo;avantage avec le premier but d&rsquo;Alexis McAllister \u00e0 la 51e minute, puis Kylian Mbappe a rat\u00e9 un penalty du Real Madrid \u00e0 la 59e minute.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"rtl\" lang=\"ar\">\ud83d\udd25 \u0645\u0627\u0643 \u0623\u0644\u064a\u0633\u062a\u064a\u0631 \u064a\u0634\u0639\u0644 \u0627\u0644\u0645\u0628\u0627\u0631\u0627\u0629 \u0628\u0647\u062f\u0641 \u0641\u064a \u0634\u0628\u0627\u0643 \u0627\u0644\u0631\u064a\u0627\u0644<a href=\"https:\/\/twitter.com\/hashtag\/%D8%AF%D9%88%D8%B1%D9%8A_%D8%A3%D8%A8%D8%B7%D8%A7%D9%84_%D8%A3%D9%88%D8%B1%D9%88%D8%A8%D8%A7?src=hash&amp;ref_src=twsrc%5Etfw\" rel=\"nofollow noopener\" target=\"_blank\">#\u062f\u0648\u0631\u064a_\u0623\u0628\u0637\u0627\u0644_\u0623\u0648\u0631\u0648\u0628\u0627<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/%D9%84%D9%8A%D9%81%D8%B1%D8%A8%D9%88%D9%84_%D8%B1%D9%8A%D8%A7%D9%84_%D9%85%D8%AF%D8%B1%D9%8A%D8%AF?src=hash&amp;ref_src=twsrc%5Etfw\" rel=\"nofollow noopener\" target=\"_blank\">#\u0644\u064a\u0641\u0631\u0628\u0648\u0644_\u0631\u064a\u0627\u0644_\u0645\u062f\u0631\u064a\u062f<\/a><a href=\"https:\/\/twitter.com\/hashtag\/UCL?src=hash&amp;ref_src=twsrc%5Etfw\" rel=\"nofollow noopener\" target=\"_blank\">#UCL<\/a> <a href=\"https:\/\/t.co\/iwlnsAqKvM\" rel=\"nofollow\">pic.twitter.com\/iwlnsAqKvM<\/a><\/p>\n<p>\u2014 beIN SPORTS (@beINSPORTS) <a href=\"https:\/\/twitter.com\/beINSPORTS\/status\/1861881600155267267?ref_src=twsrc%5Etfw\" rel=\"nofollow noopener\" target=\"_blank\">November 27, 2024<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\nMohamed Salah a eu l&rsquo;occasion de marquer son troisi\u00e8me but de l&rsquo;histoire du Real Madrid apr\u00e8s avoir remport\u00e9 un penalty, mais son tir est pass\u00e9 \u00e0 c\u00f4t\u00e9.<\/p>\n<p>Cependant, Liverpool n&rsquo;a pas \u00e9t\u00e9 grandement affect\u00e9, puisque Cody Jacobo a pu rassurer l&rsquo;\u00e9quipe d&rsquo;Arne Sloat avec une t\u00eate qu&rsquo;ils obtiendraient les trois pr\u00e9cieux points \u00e0 Anfield.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"rtl\" lang=\"ar\">\u0631\u0623\u0633\u064a\u0629 \u062e\u0627\u0643\u0628\u0648 \u062a\u0632\u064a\u062f \u0645\u0646 \u0645\u062a\u0627\u0639\u0628 \u0631\u064a\u0627\u0644 \u0645\u062f\u0631\u064a\u062f <a href=\"https:\/\/twitter.com\/hashtag\/%D8%AF%D9%88%D8%B1%D9%8A_%D8%A3%D8%A8%D8%B7%D8%A7%D9%84_%D8%A3%D9%88%D8%B1%D9%88%D8%A8%D8%A7?src=hash&amp;ref_src=twsrc%5Etfw\" rel=\"nofollow noopener\" target=\"_blank\">#\u062f\u0648\u0631\u064a_\u0623\u0628\u0637\u0627\u0644_\u0623\u0648\u0631\u0648\u0628\u0627<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/%D9%84%D9%8A%D9%81%D8%B1%D8%A8%D9%88%D9%84_%D8%B1%D9%8A%D8%A7%D9%84_%D9%85%D8%AF%D8%B1%D9%8A%D8%AF?src=hash&amp;ref_src=twsrc%5Etfw\" rel=\"nofollow noopener\" target=\"_blank\">#\u0644\u064a\u0641\u0631\u0628\u0648\u0644_\u0631\u064a\u0627\u0644_\u0645\u062f\u0631\u064a\u062f<\/a><a href=\"https:\/\/twitter.com\/hashtag\/UCL?src=hash&amp;ref_src=twsrc%5Etfw\" rel=\"nofollow noopener\" target=\"_blank\">#UCL<\/a> <a href=\"https:\/\/t.co\/Qwn4cPDLCm\" rel=\"nofollow\">pic.twitter.com\/Qwn4cPDLCm<\/a><\/p>\n<p>\u2014 beIN SPORTS (@beINSPORTS) <a href=\"https:\/\/twitter.com\/beINSPORTS\/status\/1861887558000541809?ref_src=twsrc%5Etfw\" rel=\"nofollow noopener\" target=\"_blank\">November 27, 2024<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\nCette victoire brise la s\u00e9quence d&rsquo;invincibilit\u00e9 du Real Madrid face \u00e0 Liverpool, qui s&rsquo;\u00e9tend sur 7 matches entre les deux \u00e9quipes en Ligue des Champions.<\/p>\n<p>La derni\u00e8re victoire de Liverpool avant cette confrontation contre le Royal Club remonte \u00e0 2009, \u00e9galement \u00e0 Anfield, dans un match \u00e0 quatre, \u00e0 la suite duquel les deux \u00e9quipes se sont rencontr\u00e9es \u00e0 7 reprises, notamment lors des finales de la Ligue des Champions 2018 et 2022, o\u00f9 le Real Madrid s&rsquo;est impos\u00e9. 6 fois et les deux \u00e9quipes ont \u00e9galis\u00e9 une fois.<\/p>\n<p>Avec cette victoire, Liverpool est sur le point de se qualifier pour les huiti\u00e8mes de finale de la Ligue des Champions apr\u00e8s avoir atteint le point 15 et assis seul en t\u00eate, tandis que l&rsquo;\u00e9quilibre du Real Madrid s&rsquo;est fig\u00e9 au sixi\u00e8me point \u00e0 la 24e place.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Liverpool a mis fin au n\u0153ud du Real Madrid en remportant finalement la victoire contre le Royal Club, sur le score de 2-0, au cinqui\u00e8me tour de la Ligue des Champions. Les Reds ont pris l&rsquo;avantage avec le premier but d&rsquo;Alexis McAllister \u00e0 la 51e minute, puis Kylian Mbappe a rat\u00e9 un penalty du Real [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":33224,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfio_featured_image":false,"sfio_embed_code":"","footnotes":""},"categories":[10],"tags":[],"class_list":["post-33229","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee"],"_links":{"self":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/33229","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/comments?post=33229"}],"version-history":[{"count":1,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/33229\/revisions"}],"predecessor-version":[{"id":33230,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/33229\/revisions\/33230"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/media\/33224"}],"wp:attachment":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/media?parent=33229"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/categories?post=33229"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/tags?post=33229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}