{"id":32090,"date":"2024-11-17T09:51:31","date_gmt":"2024-11-17T09:51:31","guid":{"rendered":"https:\/\/www.fanzword.com\/?p=32090"},"modified":"2024-11-17T09:51:31","modified_gmt":"2024-11-17T09:51:31","slug":"nouveaux-developpements-dans-le-dossier-du-defenseur-sauveteur-du-real-madrid","status":"publish","type":"post","link":"https:\/\/www.fanzword.com\/fr\/nouveaux-developpements-dans-le-dossier-du-defenseur-sauveteur-du-real-madrid\/","title":{"rendered":"Nouveaux d\u00e9veloppements dans le dossier du d\u00e9fenseur \u00ab\u00a0sauveteur\u00a0\u00bb du Real Madrid"},"content":{"rendered":"<p>Le journal \u00ab\u00a0Marca\u00a0\u00bb a rapport\u00e9 les derniers d\u00e9veloppements concernant le contrat du Real Madrid avec un nouveau d\u00e9fenseur central pour la prochaine p\u00e9riode de transferts hivernaux.<\/p>\n<p>Le Royal Club est confront\u00e9 \u00e0 une p\u00e9nurie num\u00e9rique \u00e0 ce poste apr\u00e8s qu&rsquo;Eder Militao a subi une rupture du ligament crois\u00e9 et le retour tardif de David Alaba de sa blessure, Antonio Rudiger est donc la seule option disponible pour entra\u00eener Carlo Ancelotti.<\/p>\n<p>Il a \u00e9t\u00e9 annonc\u00e9 apr\u00e8s la blessure de Militao que les Merengues entreraient sur le march\u00e9 hivernal pour \u00e9pauler le d\u00e9fenseur central avec au moins un joueur, et depuis, de nombreux noms ont d\u00e9j\u00e0 \u00e9t\u00e9 propos\u00e9s.<\/p>\n<p>Selon Marca, Sergio Ramos a contact\u00e9 le Real Madrid plus d&rsquo;une fois et lui a propos\u00e9 ses services, d&rsquo;autant plus que cela ne co\u00fbterait rien de significatif aux caisses du club, mais la r\u00e9ponse de la direction lui a clairement montr\u00e9 qu&rsquo;il \u00e9tait compl\u00e8tement en dehors des calculs.<\/p>\n<p>Quant \u00e0 Aymeric Laporte, la direction du Real Madrid l&rsquo;appr\u00e9cie beaucoup et le consid\u00e8re d&rsquo;un point de vue sportif comme une option id\u00e9ale, mais d&rsquo;un point de vue \u00e9conomique, il est impossible de l&rsquo;inclure car Al-Nasr s&rsquo;accroche \u00e0 au moins 30 millions d&rsquo;euros pour accepter. sa vente.<\/p>\n<p>Le nom de Jonathan Tah a \u00e9t\u00e9 pr\u00e9sent\u00e9 aux responsables du Real Madrid, et c&rsquo;est une option tr\u00e8s appr\u00e9ci\u00e9e s&rsquo;il est inclus gratuitement l&rsquo;\u00e9t\u00e9 prochain \u00e0 la fin de son contrat au Bayer Leverkusen, mais maintenant il est \u00e9galement hors des calculs.<\/p>\n<p>Restent deux noms, Mario Hermoso et Mario Gila.<\/p>\n<p>Le premier souffre d&rsquo;une blessure et des doutes subsistent \u00e0 son sujet, tandis que l&rsquo;autre est difficile \u00e0 inclure car il n&rsquo;y a pas de clause de rachat dans son contrat avec la Lazio.<\/p>\n<p>Compte tenu des donn\u00e9es, les choses deviennent plus difficiles, et peut-\u00eatre qu&rsquo;en fin de compte, le Real Madrid aura tendance \u00e0 ne pas recruter de nouveau d\u00e9fenseur central pour ne pas gaspiller ses ressources financi\u00e8res dans un accord qui ne semble pas avantageux \u00e0 long terme.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le journal \u00ab\u00a0Marca\u00a0\u00bb a rapport\u00e9 les derniers d\u00e9veloppements concernant le contrat du Real Madrid avec un nouveau d\u00e9fenseur central pour la prochaine p\u00e9riode de transferts hivernaux. Le Royal Club est confront\u00e9 \u00e0 une p\u00e9nurie num\u00e9rique \u00e0 ce poste apr\u00e8s qu&rsquo;Eder Militao a subi une rupture du ligament crois\u00e9 et le retour tardif de David Alaba [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":32086,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfio_featured_image":false,"sfio_embed_code":"","footnotes":""},"categories":[10],"tags":[],"class_list":["post-32090","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee"],"_links":{"self":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/32090","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/comments?post=32090"}],"version-history":[{"count":1,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/32090\/revisions"}],"predecessor-version":[{"id":32091,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/32090\/revisions\/32091"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/media\/32086"}],"wp:attachment":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/media?parent=32090"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/categories?post=32090"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/tags?post=32090"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}