{"id":30478,"date":"2024-11-03T09:21:18","date_gmt":"2024-11-03T09:21:18","guid":{"rendered":"https:\/\/www.fanzword.com\/?p=30478"},"modified":"2024-11-03T09:21:18","modified_gmt":"2024-11-03T09:21:18","slug":"le-real-madrid-est-profondement-preoccupe-par-le-genou-de-sa-star","status":"publish","type":"post","link":"https:\/\/www.fanzword.com\/fr\/le-real-madrid-est-profondement-preoccupe-par-le-genou-de-sa-star\/","title":{"rendered":"Le Real Madrid est \u00ab\u00a0profond\u00e9ment pr\u00e9occup\u00e9\u00a0\u00bb par le genou de sa star"},"content":{"rendered":"<p>Le r\u00e9seau \u00ab\u00a0Relevo\u00a0\u00bb a rapport\u00e9 que les responsables du Real Madrid ont de grandes inqui\u00e9tudes qui pourraient les obliger \u00e0 entrer dans le prochain Mercato hivernal pour soutenir la ligne de d\u00e9fense.<\/p>\n<p>On parle ici de la star du Real Madrid, Antonio Rudiger, qui ne serait pas en bonne forme et pourrait \u00eatre absent du terrain \u00e0 tout moment pendant une longue p\u00e9riode.<\/p>\n<h2>Rudiger souffre de douleurs au genou et son histoire est inqui\u00e9tante<\/h2>\n<p>Selon le rapport, Rudiger s&rsquo;est plaint d&rsquo;une g\u00eane au genou apr\u00e8s le dernier Clasico et a ensuite subi des tests, mais ceux-ci se sont r\u00e9v\u00e9l\u00e9s positifs et ont prouv\u00e9 qu&rsquo;il ne souffrait pas d&rsquo;une blessure grave.<\/p>\n<p>En effet, l&rsquo;international allemand \u00e9tait pr\u00eat \u00e0 participer au match de Valence avant son report, et il participera sans crise face \u00e0 Milan \u00e0 la Ligue des champions mardi.<\/p>\n<p>Cependant, le genou de Rudiger suscite de grandes inqui\u00e9tudes au sein du Real Madrid, en raison de ses ant\u00e9c\u00e9dents m\u00e9dicaux, qui incluent 5 blessures ant\u00e9rieures, et de l&rsquo;\u00e9norme pression de match \u00e0 laquelle il est expos\u00e9 cette saison.<\/p>\n<p>Le manque de joueurs oblige l&rsquo;entra\u00eeneur Carlo Ancelotti \u00e0 compter sur Rudiger dans presque tous les matches du Real Madrid, alors que le plan de base \u00e9tait de le reposer de temps en temps.<\/p>\n<p>Avec des douleurs au genou r\u00e9currentes, le Real Madrid craint que le joueur ne subisse une blessure grave qui mettrait fin \u00e0 sa saison, surtout avec ce qui a \u00e9t\u00e9 rapport\u00e9 selon lequel il souffrirait d&rsquo;arthrose pr\u00e9matur\u00e9e \u00e0 l&rsquo;un de ses genoux, bien que le club ne le fasse pas. confirmer ou infirmer le diagnostic.<\/p>\n<h2>Alaba ne reviendra pas \u00e0 l&rsquo;action de sit\u00f4t<\/h2>\n<p>Dans le m\u00eame rapport, Relevo a r\u00e9v\u00e9l\u00e9 que David Alaba ne reviendrait pas sur le terrain de sit\u00f4t.<\/p>\n<p>Le processus de r\u00e9cup\u00e9ration de la star autrichienne ne se passe pas bien, contrairement \u00e0 ce que le Real Madrid tente d&rsquo;annoncer pour rassurer les supporters.<\/p>\n<p>La date pr\u00e9vue pour le retour d&rsquo;Alaba reste janvier prochain, au d\u00e9but de la seconde moiti\u00e9 de la saison, mais compte tenu du processus de r\u00e9cup\u00e9ration tr\u00e8s lent, il pourrait \u00e9galement ne pas revenir \u00e0 cette date.<\/p>\n<h2>Le Real Madrid pourrait entrer sur le march\u00e9 hivernal pour recruter un d\u00e9fenseur<\/h2>\n<p>Il existe une grande inqui\u00e9tude pour Rudiger et la possibilit\u00e9 d&rsquo;une blessure au genou, en plus du non-retour d&rsquo;Alaba, et \u00e0 la lumi\u00e8re des diverses blessures, le Real Madrid pourrait \u00eatre contraint d&rsquo;entrer dans le Mercato hivernal pour la premi\u00e8re fois depuis des ann\u00e9es.<\/p>\n<p>La direction du Royal Club recherchera un nouveau d\u00e9fenseur central qui puisse apporter son aide \u00e0 l&rsquo;\u00e9quipe et gr\u00e2ce auquel Rudiger et Militao pourront se reposer davantage, d&rsquo;autant plus que la saison est encore pratiquement prolong\u00e9e jusqu&rsquo;en juillet prochain.<\/p>\n<p>Il convient de noter que le Real Madrid a perdu Dani Carvajal sur blessure, ainsi que le jeune d\u00e9fenseur Juan Martinez, et outre Rudiger et Militao, il n&rsquo;y a que Vallejo, qui est en mauvais \u00e9tat, et Alaba, qui est bless\u00e9.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le r\u00e9seau \u00ab\u00a0Relevo\u00a0\u00bb a rapport\u00e9 que les responsables du Real Madrid ont de grandes inqui\u00e9tudes qui pourraient les obliger \u00e0 entrer dans le prochain Mercato hivernal pour soutenir la ligne de d\u00e9fense. On parle ici de la star du Real Madrid, Antonio Rudiger, qui ne serait pas en bonne forme et pourrait \u00eatre absent du [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":30471,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfio_featured_image":false,"sfio_embed_code":"","footnotes":""},"categories":[220,222],"tags":[],"class_list":["post-30478","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-liga-fr","category-real-madrid-fr"],"_links":{"self":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/30478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/comments?post=30478"}],"version-history":[{"count":1,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/30478\/revisions"}],"predecessor-version":[{"id":30479,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/30478\/revisions\/30479"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/media\/30471"}],"wp:attachment":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/media?parent=30478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/categories?post=30478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/tags?post=30478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}