{"id":30123,"date":"2024-10-30T16:39:00","date_gmt":"2024-10-30T16:39:00","guid":{"rendered":"https:\/\/www.fanzword.com\/?p=30123"},"modified":"2024-10-30T16:39:00","modified_gmt":"2024-10-30T16:39:00","slug":"rapports-dortmund-envisage-de-licencier-nuri-sahin-et-didentifier-son-remplacant","status":"publish","type":"post","link":"https:\/\/www.fanzword.com\/fr\/rapports-dortmund-envisage-de-licencier-nuri-sahin-et-didentifier-son-remplacant\/","title":{"rendered":"Rapports : Dortmund envisage de licencier Nuri Sahin et d&rsquo;identifier son rempla\u00e7ant !"},"content":{"rendered":"<p>La direction du Borussia Dortmund a commenc\u00e9 \u00e0 \u00e9voquer l&rsquo;id\u00e9e de licencier Nuri Sahin de l&rsquo;entra\u00eenement de l&rsquo;\u00e9quipe si les r\u00e9sultats continuent de baisser dans la p\u00e9riode \u00e0 venir.<\/p>\n<p>Dortmund a quitt\u00e9 la Coupe d&rsquo;Allemagne en huiti\u00e8mes de finale apr\u00e8s avoir \u00e9t\u00e9 battu par Wolfsburg mardi en prolongation avec un but net.<\/p>\n<p>La semaine derni\u00e8re, les \u00ab Jaune et Noir \u00bb ont jou\u00e9 3 matchs dans 3 tournois, qu&rsquo;ils ont tous perdus, \u00e0 commencer par une victoire 5-3 contre le Real Madrid en Ligue des Champions, une victoire 2-1 contre Augsbourg en Bundesliga, et enfin contre Wolfsburg en coupe.<\/p>\n<p>Malgr\u00e9 les d\u00e9clarations de soutien du directeur sportif Sebastian Kehl et sa confirmation du maintien de Nuri Shaheen \u00e0 son poste, Sky confirme que l&rsquo;avenir de la Turquie est gravement menac\u00e9.<\/p>\n<p>L&rsquo;administration de Dortmund donnera \u00e0 Sahin une derni\u00e8re chance de sauver sa position, mais si les r\u00e9sultats continuent comme ils le sont dans la p\u00e9riode \u00e0 venir, il sera imm\u00e9diatement \u00e9vinc\u00e9.<\/p>\n<p>Selon Sky, l&rsquo;ancien entra\u00eeneur du Bayer Leverkusen et du Benfica, Roger Schmidt, est le premier candidat \u00e0 succ\u00e9der \u00e0 Sahin au Signal Iduna Park.<\/p>\n<p>Le joueur de 57 ans a \u00e9t\u00e9 licenci\u00e9 de la formation de Benfica en ao\u00fbt dernier, et il pourrait se f\u00e9liciter d&rsquo;un retour en Bundesliga apr\u00e8s 7 ans d&rsquo;absence depuis son exp\u00e9rience \u00e0 Leverkusen.<\/p>\n<p>Il est \u00e0 noter que Dortmund occupe la septi\u00e8me place du classement de la Ligue allemande avec 13 points en 4 victoires, un nul et 3 d\u00e9faites en 8 tours de Bundesliga jusqu&rsquo;\u00e0 pr\u00e9sent.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La direction du Borussia Dortmund a commenc\u00e9 \u00e0 \u00e9voquer l&rsquo;id\u00e9e de licencier Nuri Sahin de l&rsquo;entra\u00eenement de l&rsquo;\u00e9quipe si les r\u00e9sultats continuent de baisser dans la p\u00e9riode \u00e0 venir. Dortmund a quitt\u00e9 la Coupe d&rsquo;Allemagne en huiti\u00e8mes de finale apr\u00e8s avoir \u00e9t\u00e9 battu par Wolfsburg mardi en prolongation avec un but net. La semaine derni\u00e8re, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":30118,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfio_featured_image":false,"sfio_embed_code":"","footnotes":""},"categories":[211],"tags":[],"class_list":["post-30123","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bundesliga"],"_links":{"self":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/30123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/comments?post=30123"}],"version-history":[{"count":1,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/30123\/revisions"}],"predecessor-version":[{"id":30124,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/30123\/revisions\/30124"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/media\/30118"}],"wp:attachment":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/media?parent=30123"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/categories?post=30123"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/tags?post=30123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}