{"id":29647,"date":"2024-10-28T09:20:02","date_gmt":"2024-10-28T09:20:02","guid":{"rendered":"https:\/\/www.fanzword.com\/?p=29647"},"modified":"2024-10-28T09:20:02","modified_gmt":"2024-10-28T09:20:02","slug":"rapports-latletico-madrid-envisage-de-licencier-simeone","status":"publish","type":"post","link":"https:\/\/www.fanzword.com\/fr\/rapports-latletico-madrid-envisage-de-licencier-simeone\/","title":{"rendered":"Rapports : l&rsquo;Atletico Madrid envisage de licencier Simeone"},"content":{"rendered":"<p>Selon la presse espagnole, la direction de l&rsquo;Atletico Madrid a commenc\u00e9 \u00e0 chercher un nouvel entra\u00eeneur pour diriger l&rsquo;\u00e9quipe, apr\u00e8s avoir commenc\u00e9 \u00e0 douter des capacit\u00e9s de l&rsquo;entra\u00eeneur Diego Simeone.<\/p>\n<p>La d\u00e9cision du club espagnol intervient dans le contexte d&rsquo;une baisse significative des r\u00e9sultats des Rojiblancos r\u00e9cemment, compl\u00e9t\u00e9e par une d\u00e9faite 1-0 contre le Real Betis dimanche en Liga.<\/p>\n<p>Selon ce qui a \u00e9t\u00e9 rapport\u00e9 par les m\u00e9dias, malgr\u00e9 la haute estime dont Simeone est tenu au sein de l&rsquo;Atletico, la col\u00e8re contre lui a fortement augment\u00e9 ces derniers temps, y compris de la part de ses partisans les plus fid\u00e8les, en raison de la fa\u00e7on dont l&rsquo;\u00e9quipe se comporte avec lui cette saison.<\/p>\n<p>Pour cette raison, la direction de l&rsquo;Atletico a commenc\u00e9 \u00e0 rechercher le march\u00e9 des entra\u00eeneurs dans l&rsquo;espoir de trouver le successeur id\u00e9al pour lui, mais jusqu&rsquo;\u00e0 pr\u00e9sent, elle n&rsquo;a pas pris la d\u00e9cision de le licencier et donnera \u00e0 Simeone une derni\u00e8re chance de sauver son poste.<\/p>\n<p>L&rsquo;entra\u00eeneur argentin doit prouver qu&rsquo;il peut changer radicalement la situation au Wanda Metropolitano, sinon le licenciement sera son destin in\u00e9vitable d&rsquo;ici quelques semaines.<\/p>\n<p>A noter que l&rsquo;Atletico Madrid a \u00e9t\u00e9 battu cette saison en Ligue des Champions 4-0 par Benfica et 3-1 par Lille, et qu&rsquo;il occupe \u00e9galement la quatri\u00e8me place du classement de la Liga, \u00e0 10 points du leader Barcelone.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Selon la presse espagnole, la direction de l&rsquo;Atletico Madrid a commenc\u00e9 \u00e0 chercher un nouvel entra\u00eeneur pour diriger l&rsquo;\u00e9quipe, apr\u00e8s avoir commenc\u00e9 \u00e0 douter des capacit\u00e9s de l&rsquo;entra\u00eeneur Diego Simeone. La d\u00e9cision du club espagnol intervient dans le contexte d&rsquo;une baisse significative des r\u00e9sultats des Rojiblancos r\u00e9cemment, compl\u00e9t\u00e9e par une d\u00e9faite 1-0 contre le Real [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":29642,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfio_featured_image":false,"sfio_embed_code":"","footnotes":""},"categories":[220],"tags":[],"class_list":["post-29647","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-liga-fr"],"_links":{"self":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/29647","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/comments?post=29647"}],"version-history":[{"count":1,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/29647\/revisions"}],"predecessor-version":[{"id":29648,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/29647\/revisions\/29648"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/media\/29642"}],"wp:attachment":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/media?parent=29647"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/categories?post=29647"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/tags?post=29647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}