{"id":29553,"date":"2024-10-27T09:51:21","date_gmt":"2024-10-27T09:51:21","guid":{"rendered":"https:\/\/www.fanzword.com\/?p=29553"},"modified":"2024-10-27T09:51:21","modified_gmt":"2024-10-27T09:51:21","slug":"yamal-se-remet-au-real-madrid-a-sa-maniere","status":"publish","type":"post","link":"https:\/\/www.fanzword.com\/fr\/yamal-se-remet-au-real-madrid-a-sa-maniere\/","title":{"rendered":"Yamal se remet au Real Madrid \u00e0 sa mani\u00e8re"},"content":{"rendered":"<p>La star barcelonaise Lamine Yamal a exprim\u00e9 \u00e0 quel point il \u00e9tait heureux de la victoire 4-0 du club catalan au Clasico et du but historique qu&rsquo;il a marqu\u00e9 contre le Real Madrid samedi.<\/p>\n<p>S&rsquo;exprimant apr\u00e8s le match, Yamal a \u00e9t\u00e9 interrog\u00e9 sur le but qu&rsquo;il avait marqu\u00e9 avec son droit, ce \u00e0 quoi il a r\u00e9pondu : \u00ab\u00a0Je pense que les joueurs du Real Madrid ne savaient pas que j&rsquo;avais un pied droit, donc quand j&rsquo;en ai eu besoin aujourd&rsquo;hui, j&rsquo;ai d\u00fb l&rsquo;utiliser. il.\u00a0\u00bb<\/p>\n<p>Il a \u00e9galement ajout\u00e9 : \u00ab\u00a0Nous pensons que nous avons la meilleure \u00e9quipe du monde\u00a0\u00bb.<\/p>\n<p>Il a poursuivi \u00e0 ce sujet en disant : \u00ab\u00a0Ils disaient que nous ne gagnions que contre des \u00e9quipes r\u00e9guli\u00e8res. Maintenant, nous sommes vainqueurs 4-0 du Real Madrid et dans son stade. Nous avons prouv\u00e9 que nous \u00e9tions capables de gagner contre n&rsquo;importe quel concurrent\u00a0\u00bb.<\/p>\n<p>Il a conclu : \u00ab\u00a0Je veux maintenant dire : vive Barcelone ! Continuons ce que nous faisons et gagnons la Liga cette saison.\u00a0\u00bb<\/p>\n<p>Il convient de noter qu&rsquo;avec le but qu&rsquo;il a marqu\u00e9 pour le Real Madrid, Yamal est devenu le plus jeune joueur \u00e0 marquer un but lors du Clasico, \u00e0 l&rsquo;\u00e2ge de seulement 17 ans et 106 jours.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La star barcelonaise Lamine Yamal a exprim\u00e9 \u00e0 quel point il \u00e9tait heureux de la victoire 4-0 du club catalan au Clasico et du but historique qu&rsquo;il a marqu\u00e9 contre le Real Madrid samedi. S&rsquo;exprimant apr\u00e8s le match, Yamal a \u00e9t\u00e9 interrog\u00e9 sur le but qu&rsquo;il avait marqu\u00e9 avec son droit, ce \u00e0 quoi il [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":29547,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfio_featured_image":false,"sfio_embed_code":"","footnotes":""},"categories":[221,220,222],"tags":[],"class_list":["post-29553","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-barcelona-fr","category-la-liga-fr","category-real-madrid-fr"],"_links":{"self":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/29553","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/comments?post=29553"}],"version-history":[{"count":1,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/29553\/revisions"}],"predecessor-version":[{"id":29554,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/29553\/revisions\/29554"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/media\/29547"}],"wp:attachment":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/media?parent=29553"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/categories?post=29553"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/tags?post=29553"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}