{"id":28858,"date":"2024-10-21T14:01:51","date_gmt":"2024-10-21T14:01:51","guid":{"rendered":"https:\/\/www.fanzword.com\/?p=28858"},"modified":"2024-10-21T14:01:51","modified_gmt":"2024-10-21T14:01:51","slug":"quelle-est-la-verite-sur-le-transfert-soudain-darda-guler-a-la-juventus","status":"publish","type":"post","link":"https:\/\/www.fanzword.com\/fr\/quelle-est-la-verite-sur-le-transfert-soudain-darda-guler-a-la-juventus\/","title":{"rendered":"Quelle est la v\u00e9rit\u00e9 sur le transfert soudain d&rsquo;Arda Guler \u00e0 la Juventus ?"},"content":{"rendered":"<p>Tous les fans de football ont \u00e9t\u00e9 surpris par un tweet sur le compte officiel anglais de la Juventus annon\u00e7ant le transfert de la star du Real Madrid Arda Guler dans les rangs du club italien.<\/p>\n<p>Le tweet disait : \u00ab\u00a0Bienvenue \u00e0 la Juventus, Arda Guler ! La star la plus prometteuse du monde du football rejoint d\u00e9sormais la Juventus. \u00cates-vous pr\u00eats \u00e0 \u00e9crire l&rsquo;histoire ensemble dans ce nouveau voyage ?\u00a0\u00bb<\/p>\n<p>Il ne fait aucun doute que la nouvelle \u00e0 premi\u00e8re vue a sembl\u00e9 tr\u00e8s surprenante \u00e9tant donn\u00e9 qu&rsquo;il s&rsquo;agit d&rsquo;un r\u00e9cit officiel, en plus du fait que nous vivons au mois d&rsquo;octobre, c&rsquo;est-\u00e0-dire loin de la p\u00e9riode des transferts et des deals que cela peut inclure, et Guler n&rsquo;a jamais \u00e9t\u00e9 li\u00e9 \u00e0 un transfert \u00e0 la Juventus.<\/p>\n<p>Quelques minutes plus tard, le compte officiel de la Juventus en italien publiait un tweet annon\u00e7ant que le compte anglais avait \u00e9t\u00e9 pirat\u00e9.<\/p>\n<p>Il semble clair que ceux qui ont pirat\u00e9 le compte anglais de la Juventus \u00e9taient des Turcs, puisqu&rsquo;ils ont ensuite publi\u00e9 un tweet sarcastique du pr\u00e9sident de Fenerbahce.<\/p>\n<p>Guler, 18 ans, est actuellement au Real Madrid et se pr\u00e9pare \u00e0 jouer mardi contre le Borussia Dortmund en Ligue des champions.<\/p>\n<p>Il est \u00e0 noter que Guler s&rsquo;est plaint \u00e0 plusieurs reprises de ne pas avoir beaucoup particip\u00e9 aux matches cette saison et, ces derni\u00e8res semaines, certains rapports ont commenc\u00e9 \u00e0 indiquer qu&rsquo;il pourrait partir en pr\u00eat \u00e0 un autre club lors du prochain march\u00e9 des transferts d&rsquo;hiver.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tous les fans de football ont \u00e9t\u00e9 surpris par un tweet sur le compte officiel anglais de la Juventus annon\u00e7ant le transfert de la star du Real Madrid Arda Guler dans les rangs du club italien. Le tweet disait : \u00ab\u00a0Bienvenue \u00e0 la Juventus, Arda Guler ! La star la plus prometteuse du monde du [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":28854,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfio_featured_image":false,"sfio_embed_code":"","footnotes":""},"categories":[220,222,217,233],"tags":[],"class_list":["post-28858","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-liga-fr","category-real-madrid-fr","category-serie-a-fr","category-transferts"],"_links":{"self":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/28858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/comments?post=28858"}],"version-history":[{"count":1,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/28858\/revisions"}],"predecessor-version":[{"id":28859,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/28858\/revisions\/28859"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/media\/28854"}],"wp:attachment":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/media?parent=28858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/categories?post=28858"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/tags?post=28858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}