{"id":27926,"date":"2024-10-13T08:49:00","date_gmt":"2024-10-13T08:49:00","guid":{"rendered":"https:\/\/www.fanzword.com\/?p=27926"},"modified":"2024-10-13T08:49:00","modified_gmt":"2024-10-13T08:49:00","slug":"barcelone-elabore-un-plan-ideal-pour-preparer-olmo-au-clasico","status":"publish","type":"post","link":"https:\/\/www.fanzword.com\/fr\/barcelone-elabore-un-plan-ideal-pour-preparer-olmo-au-clasico\/","title":{"rendered":"Barcelone \u00e9labore un plan id\u00e9al pour pr\u00e9parer Olmo au Cl\u00e1sico"},"content":{"rendered":"<p>Le staff m\u00e9dical de Barcelone a \u00e9labor\u00e9 un plan qui semble id\u00e9al pour pr\u00e9parer Dani Olmo \u00e0 participer au match du Real Madrid pr\u00e9vu le 26 octobre au stade Santiago Bernab\u00e9u.<\/p>\n<p>L&rsquo;international espagnol est absent depuis plus d&rsquo;un mois apr\u00e8s avoir subi une blessure musculaire, et on craint \u00e0 Barcelone qu&rsquo;il subisse un revers, et c&rsquo;est pour cette raison qu&rsquo;il existe un plan pr\u00e9cis pour pr\u00e9parer son retour.<\/p>\n<p>Selon le journal \u00ab\u00a0Mundo Deportivo\u00a0\u00bb, Olmo ne jouera que 30 minutes contre S\u00e9ville lors du premier match de Barcelone apr\u00e8s la tr\u00eave internationale.<\/p>\n<p>Une fois rassur\u00e9 apr\u00e8s la confrontation que tout va bien pour l&rsquo;ancien joueur de Leipzig, sa p\u00e9riode de participation au prochain match contre le Bayern Munich sera port\u00e9e \u00e0 une moiti\u00e9 compl\u00e8te.<\/p>\n<p>Si les choses se passent bien, on pourra compter sur le joueur de 26 ans principalement contre le Real Madrid, m\u00eame si les instructions exigent qu&rsquo;il ne joue au maximum que 60 minutes lors du Cl\u00e1sico.<\/p>\n<p>Il est \u00e0 noter qu&rsquo;Olmo, depuis son arriv\u00e9e \u00e0 Barcelone l&rsquo;\u00e9t\u00e9 dernier, a particip\u00e9 \u00e0 3 matches au cours desquels il a r\u00e9ussi \u00e0 marquer 3 buts.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le staff m\u00e9dical de Barcelone a \u00e9labor\u00e9 un plan qui semble id\u00e9al pour pr\u00e9parer Dani Olmo \u00e0 participer au match du Real Madrid pr\u00e9vu le 26 octobre au stade Santiago Bernab\u00e9u. L&rsquo;international espagnol est absent depuis plus d&rsquo;un mois apr\u00e8s avoir subi une blessure musculaire, et on craint \u00e0 Barcelone qu&rsquo;il subisse un revers, et [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":27922,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfio_featured_image":false,"sfio_embed_code":"","footnotes":""},"categories":[221,220],"tags":[],"class_list":["post-27926","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-barcelona-fr","category-la-liga-fr"],"_links":{"self":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/27926","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/comments?post=27926"}],"version-history":[{"count":1,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/27926\/revisions"}],"predecessor-version":[{"id":27927,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/27926\/revisions\/27927"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/media\/27922"}],"wp:attachment":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/media?parent=27926"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/categories?post=27926"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/tags?post=27926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}