{"id":27781,"date":"2024-10-12T07:55:25","date_gmt":"2024-10-12T07:55:25","guid":{"rendered":"https:\/\/www.fanzword.com\/?p=27781"},"modified":"2024-10-12T07:55:25","modified_gmt":"2024-10-12T07:55:25","slug":"surprise-le-maroc-est-plus-proche-que-madrid-daccueillir-la-finale-de-la-coupe-du-monde-2030","status":"publish","type":"post","link":"https:\/\/www.fanzword.com\/fr\/surprise-le-maroc-est-plus-proche-que-madrid-daccueillir-la-finale-de-la-coupe-du-monde-2030\/","title":{"rendered":"Surprise : le Maroc est plus proche que Madrid d&rsquo;accueillir la finale de la Coupe du monde 2030"},"content":{"rendered":"<p>Le conseiller sportif de la municipalit\u00e9 de Barcelone, David Escudi, a cr\u00e9\u00e9 la surprise en confirmant que le stade Santiago Bernabeu ne pourrait pas accueillir la finale de la Coupe du monde 2030 car il \u00ab ne r\u00e9pond pas au cahier des charges \u00bb.<\/p>\n<p>L&rsquo;Espagne, avec le Portugal et le Maroc, accueillera la Coupe du monde 2030, et la comp\u00e9tition est grande entre le pays des Matadors et la \u00ab patrie du libre \u00bb pour le stade qui accueillera la finale.<\/p>\n<p>On a dit que le fief du Real Madrid, le Santiago Bernabeu, \u00e9tait le plus proche, tandis que Barcelone estime que son stade Camp Nou, apr\u00e8s les agrandissements, serait le choix id\u00e9al, tandis que le Maroc souhaite accueillir la finale dans le nouveau stade de Casablanca.<\/p>\n<p>Escudi a parl\u00e9 de cette pol\u00e9mique en termes clairs, au cours duquel il a d\u00e9clar\u00e9 : \u00ab\u00a0Je suis surpris qu&rsquo;on ait propos\u00e9 que le stade Santiago Bernabeu accueille la finale\u00a0\u00bb.<\/p>\n<p>Il a \u00e9galement ajout\u00e9 : \u00ab\u00a0Le stade de Madrid ne r\u00e9pond pas aux sp\u00e9cifications de la FIFA\u00a0\u00bb.<\/p>\n<p>Il a conclu : \u00ab\u00a0La v\u00e9ritable comp\u00e9tition pour accueillir la finale de la Coupe du monde 2030 se d\u00e9roulera entre le Camp Nou et le nouveau stade marocain en construction \u00e0 Casablanca\u00a0\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le conseiller sportif de la municipalit\u00e9 de Barcelone, David Escudi, a cr\u00e9\u00e9 la surprise en confirmant que le stade Santiago Bernabeu ne pourrait pas accueillir la finale de la Coupe du monde 2030 car il \u00ab ne r\u00e9pond pas au cahier des charges \u00bb. L&rsquo;Espagne, avec le Portugal et le Maroc, accueillera la Coupe du [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":27777,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfio_featured_image":false,"sfio_embed_code":"","footnotes":""},"categories":[220,222],"tags":[],"class_list":["post-27781","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-liga-fr","category-real-madrid-fr"],"_links":{"self":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/27781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/comments?post=27781"}],"version-history":[{"count":1,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/27781\/revisions"}],"predecessor-version":[{"id":27782,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/27781\/revisions\/27782"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/media\/27777"}],"wp:attachment":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/media?parent=27781"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/categories?post=27781"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/tags?post=27781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}