{"id":27711,"date":"2024-10-11T08:09:56","date_gmt":"2024-10-11T08:09:56","guid":{"rendered":"https:\/\/www.fanzword.com\/?p=27711"},"modified":"2024-10-11T08:09:56","modified_gmt":"2024-10-11T08:09:56","slug":"les-malheurs-du-real-madrid-continuent-sa-star-ne-reviendra-pas-de-sitot","status":"publish","type":"post","link":"https:\/\/www.fanzword.com\/fr\/les-malheurs-du-real-madrid-continuent-sa-star-ne-reviendra-pas-de-sitot\/","title":{"rendered":"Les malheurs du Real Madrid continuent&#8230; sa star ne reviendra pas de sit\u00f4t !"},"content":{"rendered":"<p>Les crises de blessures au Real Madrid se poursuivent et la derni\u00e8re victime est David Alaba.<\/p>\n<p>L&rsquo;international autrichien est absent du Royal Club depuis d\u00e9cembre dernier suite \u00e0 une rupture des ligaments crois\u00e9s et internes, et la date pr\u00e9vue de son retour \u00e9tait ce mois d&rsquo;octobre.<\/p>\n<p>Mais selon ce qui a \u00e9t\u00e9 rapport\u00e9 par le r\u00e9seau Relevo, Alaba ne s&rsquo;est pas compl\u00e8tement remis de sa blessure, et ne reviendra pas sur le terrain de sit\u00f4t.<\/p>\n<p>Le joueur de 31 ans aura besoin d&rsquo;au moins deux mois pour achever sa convalescence et il ne devrait pas revenir avant janvier prochain.<\/p>\n<p>Carlo Ancelotti comptait sur le retour d&rsquo;Alaba pour assurer le poste de d\u00e9fenseur central compte tenu des blessures et du manque de nombre, et il aurait \u00e9galement pu compter sur lui au milieu du terrain ou au poste d&rsquo;arri\u00e8re gauche.<\/p>\n<p>En fin de compte, Ancelotti et le Real Madrid devront patienter jusqu&rsquo;en 2025 pour r\u00e9cup\u00e9rer Alaba, ce qui repr\u00e9sente un coup dur pour les projets du Royal Club pour le premier tour de cette saison.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les crises de blessures au Real Madrid se poursuivent et la derni\u00e8re victime est David Alaba. L&rsquo;international autrichien est absent du Royal Club depuis d\u00e9cembre dernier suite \u00e0 une rupture des ligaments crois\u00e9s et internes, et la date pr\u00e9vue de son retour \u00e9tait ce mois d&rsquo;octobre. Mais selon ce qui a \u00e9t\u00e9 rapport\u00e9 par le [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":27707,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfio_featured_image":false,"sfio_embed_code":"","footnotes":""},"categories":[220,222],"tags":[],"class_list":["post-27711","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-liga-fr","category-real-madrid-fr"],"_links":{"self":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/27711","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/comments?post=27711"}],"version-history":[{"count":1,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/27711\/revisions"}],"predecessor-version":[{"id":27712,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/27711\/revisions\/27712"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/media\/27707"}],"wp:attachment":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/media?parent=27711"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/categories?post=27711"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/tags?post=27711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}