{"id":27244,"date":"2024-10-06T09:51:05","date_gmt":"2024-10-06T09:51:05","guid":{"rendered":"https:\/\/www.fanzword.com\/?p=27244"},"modified":"2024-10-06T09:51:05","modified_gmt":"2024-10-06T09:51:05","slug":"lhumain-messi-rend-un-enfant-heureux-a-sa-maniere-video","status":"publish","type":"post","link":"https:\/\/www.fanzword.com\/fr\/lhumain-messi-rend-un-enfant-heureux-a-sa-maniere-video\/","title":{"rendered":"\u00ab\u00a0L&rsquo;Humain\u00a0\u00bb Messi rend un enfant heureux \u00e0 sa mani\u00e8re (vid\u00e9o)"},"content":{"rendered":"<p>Lionel Messi a de nouveau attir\u00e9 l&rsquo;attention dans la Ligue am\u00e9ricaine, mais cette fois non pas avec un but ou une passe d\u00e9cisive, mais avec un geste humanitaire.<\/p>\n<p>Messi a particip\u00e9 dimanche matin au match de son \u00e9quipe contre l&rsquo;Inter Miami contre Toronto, lorsque les co\u00e9quipiers de la puce ont gagn\u00e9 par un but sans r\u00e9ponse.<\/p>\n<p>Un enfant a saut\u00e9 sur le terrain et s&rsquo;est approch\u00e9 de Messi pendant le match, essayant de prendre une photo avec lui, et le garde du corps de l&rsquo;Argentin s&rsquo;est \u00e9galement d\u00e9plac\u00e9 sur le terrain pour l&rsquo;arr\u00eater.<\/p>\n<p>Mais \u00e0 ce moment-l\u00e0, Messi est intervenu et leur a demand\u00e9 de le quitter, et l&rsquo;enfant a pris la photo dont il r\u00eavait avec le joueur de 37 ans.<\/p>\n<p>L&rsquo;enfant a quitt\u00e9 le terrain avec la main lev\u00e9e et son visage montrait de la joie face \u00e0 la fa\u00e7on dont Messi l&rsquo;avait trait\u00e9 et lui avait permis de prendre la photo.<\/p>\n<p>La photo parle..<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"rtl\" lang=\"ar\">\u0627\u0644\u0623\u0633\u0637\u0648\u0631\u0629 \u0645\u064a\u0633\u064a \u064a\u0633\u0645\u062d \u0644\u0644\u0645\u0634\u062c\u0639 \u0628\u0627\u0644\u062a\u0642\u0627\u0637 \u0635\u0648\u0631\u0629 \u0645\u0639\u0647 \ud83d\ude0d\ud83d\ude0d\ud83d\ude0d <a href=\"https:\/\/t.co\/r5J6Xb9s9f\" rel=\"nofollow\">pic.twitter.com\/r5J6Xb9s9f<\/a><\/p>\n<p>\u2014 Messi World (@M10GOAT) <a href=\"https:\/\/twitter.com\/M10GOAT\/status\/1842690661688156665?ref_src=twsrc%5Etfw\" rel=\"nofollow noopener\" target=\"_blank\">October 5, 2024<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lionel Messi a de nouveau attir\u00e9 l&rsquo;attention dans la Ligue am\u00e9ricaine, mais cette fois non pas avec un but ou une passe d\u00e9cisive, mais avec un geste humanitaire. Messi a particip\u00e9 dimanche matin au match de son \u00e9quipe contre l&rsquo;Inter Miami contre Toronto, lorsque les co\u00e9quipiers de la puce ont gagn\u00e9 par un but sans [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":27240,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfio_featured_image":false,"sfio_embed_code":"","footnotes":""},"categories":[226],"tags":[],"class_list":["post-27244","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lionel-messi-fr"],"_links":{"self":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/27244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/comments?post=27244"}],"version-history":[{"count":1,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/27244\/revisions"}],"predecessor-version":[{"id":27245,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/27244\/revisions\/27245"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/media\/27240"}],"wp:attachment":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/media?parent=27244"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/categories?post=27244"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/tags?post=27244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}