{"id":26986,"date":"2024-10-02T22:09:44","date_gmt":"2024-10-02T22:09:44","guid":{"rendered":"https:\/\/www.fanzword.com\/?p=26986"},"modified":"2024-10-02T22:09:44","modified_gmt":"2024-10-02T22:09:44","slug":"apres-258-jours-sans-defaite-le-real-madrid-chute-a-lille-et-ancelotti-reconnait-son-echec","status":"publish","type":"post","link":"https:\/\/www.fanzword.com\/fr\/apres-258-jours-sans-defaite-le-real-madrid-chute-a-lille-et-ancelotti-reconnait-son-echec\/","title":{"rendered":"Apr\u00e8s 258 jours sans d\u00e9faite&#8230; Le Real Madrid chute \u00e0 Lille et Ancelotti reconna\u00eet son \u00e9chec"},"content":{"rendered":"<p>La s\u00e9quence de 36 matchs sans d\u00e9faite du Real Madrid tous tournois confondus a pris fin apr\u00e8s la d\u00e9faite du Royal Club face \u00e0 Lille 1-0 au deuxi\u00e8me tour de la phase de Ligue des Champions.<\/p>\n<p>La derni\u00e8re d\u00e9faite du Real Madrid remonte \u00e0 la saison derni\u00e8re face \u00e0 l&rsquo;Atletico Madrid en Coupe du Roi, et depuis lors, les Merengues n&rsquo;ont perdu aucun match de tous les tournois sur une p\u00e9riode de 258 jours.<\/p>\n<p>Carlo Ancelotti a comment\u00e9 la d\u00e9faite contre Lille en d\u00e9clarant : \u00ab\u00a0Lille \u00e9tait le meilleur et m\u00e9ritait de gagner. Nous aurions pu \u00e9galiser dans les derniers instants, mais ce n&rsquo;\u00e9tait franchement pas m\u00e9rit\u00e9.\u00a0\u00bb<\/p>\n<p>Il a \u00e9galement ajout\u00e9 : \u00ab\u00a0C&rsquo;est vraiment difficile d&rsquo;analyser le match. Nous avons \u00e9t\u00e9 mauvais dans tous les aspects. Nous ne nous sommes pas cr\u00e9\u00e9s d&rsquo;occasions et n&rsquo;avons pas poss\u00e9d\u00e9 le ballon. Nous \u00e9tions presque sans id\u00e9es.\u00a0\u00bb<\/p>\n<p>Il a poursuivi : \u00ab\u00a0C&rsquo;est un mauvais match. Nous avons montr\u00e9 une mauvaise image et avons de mauvais sentiments. Il n&rsquo;y a aucune excuse pour ce qui s&rsquo;est pass\u00e9. Nous devons nous am\u00e9liorer.\u00a0\u00bb<\/p>\n<p>Il a conclu : \u00ab\u00a0J&rsquo;accepte enti\u00e8rement les critiques. Nous avons \u00e9t\u00e9 tr\u00e8s mauvais, mais je dis que la d\u00e9faite contre l&rsquo;Atletico Madrid en janvier dernier nous a aid\u00e9 \u00e0 changer. Nous esp\u00e9rons que cela se produira \u00e9galement aujourd&rsquo;hui.\u00a0\u00bb<\/p>\n<p>Samedi prochain, le Real Madrid rencontrera Villarreal au stade Santiago Bernabeu de la Liga apr\u00e8s avoir fait match nul au dernier tour contre l&rsquo;Atletico Madrid 1-1.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La s\u00e9quence de 36 matchs sans d\u00e9faite du Real Madrid tous tournois confondus a pris fin apr\u00e8s la d\u00e9faite du Royal Club face \u00e0 Lille 1-0 au deuxi\u00e8me tour de la phase de Ligue des Champions. La derni\u00e8re d\u00e9faite du Real Madrid remonte \u00e0 la saison derni\u00e8re face \u00e0 l&rsquo;Atletico Madrid en Coupe du Roi, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":26982,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfio_featured_image":false,"sfio_embed_code":"","footnotes":""},"categories":[251,222],"tags":[],"class_list":["post-26986","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ligue-des-champions","category-real-madrid-fr"],"_links":{"self":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/26986","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/comments?post=26986"}],"version-history":[{"count":1,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/26986\/revisions"}],"predecessor-version":[{"id":26987,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/26986\/revisions\/26987"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/media\/26982"}],"wp:attachment":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/media?parent=26986"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/categories?post=26986"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/tags?post=26986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}