{"id":26780,"date":"2024-09-30T12:39:53","date_gmt":"2024-09-30T12:39:53","guid":{"rendered":"https:\/\/www.fanzword.com\/?p=26780"},"modified":"2024-09-30T12:39:53","modified_gmt":"2024-09-30T12:39:53","slug":"une-blessure-prive-le-real-madrid-de-courtois-pour-une-periode-relativement-longue","status":"publish","type":"post","link":"https:\/\/www.fanzword.com\/fr\/une-blessure-prive-le-real-madrid-de-courtois-pour-une-periode-relativement-longue\/","title":{"rendered":"Une blessure prive le Real Madrid de Courtois pour une p\u00e9riode relativement longue"},"content":{"rendered":"<p>Le Real Madrid a annonc\u00e9 dans un communiqu\u00e9 officiel les d\u00e9tails de la blessure de Thibaut Courtois, subie dimanche lors du match contre l&rsquo;Atletico Madrid.<\/p>\n<p>L&rsquo;entra\u00eeneur Carlo Ancelotti a d\u00e9clar\u00e9 apr\u00e8s le derby que le gardien belge souffrait d&rsquo;une blessure musculaire et qu&rsquo;il subirait des tests lundi pour d\u00e9terminer la dur\u00e9e de son absence du terrain.<\/p>\n<p>Selon le communiqu\u00e9 du Royal Club, Courtois souffre d&rsquo;une blessure au muscle conjonctif de la jambe gauche, sans pr\u00e9ciser la dur\u00e9e de son absence.<\/p>\n<p>Marca a indiqu\u00e9 que le joueur de 32 ans serait absent du terrain pendant au moins 3 semaines.<\/p>\n<p>Ainsi, Courtois ne participera pas aux matchs entre Lille et Villarreal avant la tr\u00eave internationale, et son retour se fera \u00e0 moins de trouver du nouveau contre le Celta Vigo le 19 octobre.<\/p>\n<p>Courtois tentera de r\u00e9cup\u00e9rer \u00e0 temps pour pouvoir participer au Cl\u00e1sico contre Barcelone le 29 octobre au stade Santiago Bernabeu.<\/p>\n<p>A noter qu&rsquo;en l&rsquo;absence de Courtois, Andriy Lunin aura enfin l&rsquo;opportunit\u00e9 de participer \u00e0 au moins deux matches.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Real Madrid a annonc\u00e9 dans un communiqu\u00e9 officiel les d\u00e9tails de la blessure de Thibaut Courtois, subie dimanche lors du match contre l&rsquo;Atletico Madrid. L&rsquo;entra\u00eeneur Carlo Ancelotti a d\u00e9clar\u00e9 apr\u00e8s le derby que le gardien belge souffrait d&rsquo;une blessure musculaire et qu&rsquo;il subirait des tests lundi pour d\u00e9terminer la dur\u00e9e de son absence du [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":26776,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfio_featured_image":false,"sfio_embed_code":"","footnotes":""},"categories":[221,220],"tags":[],"class_list":["post-26780","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-barcelona-fr","category-la-liga-fr"],"_links":{"self":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/26780","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/comments?post=26780"}],"version-history":[{"count":1,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/26780\/revisions"}],"predecessor-version":[{"id":26781,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/26780\/revisions\/26781"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/media\/26776"}],"wp:attachment":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/media?parent=26780"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/categories?post=26780"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/tags?post=26780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}