{"id":26718,"date":"2024-09-29T22:12:27","date_gmt":"2024-09-29T22:12:27","guid":{"rendered":"https:\/\/www.fanzword.com\/?p=26718"},"modified":"2024-09-29T22:12:27","modified_gmt":"2024-09-29T22:12:27","slug":"simeone-tient-courtois-pour-responsable-des-evenements-du-derby","status":"publish","type":"post","link":"https:\/\/www.fanzword.com\/fr\/simeone-tient-courtois-pour-responsable-des-evenements-du-derby\/","title":{"rendered":"Simeone tient Courtois pour responsable des \u00e9v\u00e9nements du derby"},"content":{"rendered":"<p>L&rsquo;entra\u00eeneur de l&rsquo;Atletico Madrid, Diego Simeone, estime que Thibaut Courtois est en faute et \u00e0 l&rsquo;origine de la crise survenue lors du derby contre le Real Madrid.<\/p>\n<p>Le match entre l&rsquo;Atletico et le Real Madrid a \u00e9t\u00e9 arr\u00eat\u00e9 pendant environ une demi-heure apr\u00e8s que des supporters du stade Wanda Metropolitano ont lanc\u00e9 des briquets et des projectiles sur Courtois.<\/p>\n<p>Un instantan\u00e9 a montr\u00e9 plus tard que Courtois a c\u00e9l\u00e9br\u00e9 le but d&rsquo;Eder Militao devant les supporters de l&rsquo;Atletico, ce que Simeone consid\u00e9rait comme un mauvais comportement et qui \u00e9tait la cause de toute la crise.<\/p>\n<p>\u00ab\u00a0Vous pouvez c\u00e9l\u00e9brer le but comme vous le souhaitez, mais pas en provoquant les supporters ou en faisant des gestes\u00a0\u00bb, a d\u00e9clar\u00e9 Simeone apr\u00e8s le match.<\/p>\n<p>Il a \u00e9galement ajout\u00e9 : \u00ab\u00a0Cela ne justifie pas ce qui s&rsquo;est pass\u00e9 de la part des fans, mais il n&rsquo;y a aucune raison non plus pour ce que Courtois a fait.\u00a0\u00bb<\/p>\n<p>Il a conclu : \u00ab\u00a0Le club ne doit pas permettre que cela se produise. La personne qui a lanc\u00e9 les projectiles ne doit pas \u00eatre sur le terrain et ceux qui ont provoqu\u00e9 les supporters doivent \u00eatre punis.\u00a0\u00bb<\/p>\n<p>Courtois a jou\u00e9 avec l&rsquo;Atletico Madrid pendant des ann\u00e9es en pr\u00eat de Chelsea, avant de rejoindre le Real Madrid en 2018.<\/p>\n<p>Le match entre le Real Madrid et l&rsquo;Atletico Madrid s&rsquo;est termin\u00e9 apr\u00e8s sa reprise par un match nul positif entre les deux \u00e9quipes, un \u00e0 un.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;entra\u00eeneur de l&rsquo;Atletico Madrid, Diego Simeone, estime que Thibaut Courtois est en faute et \u00e0 l&rsquo;origine de la crise survenue lors du derby contre le Real Madrid. Le match entre l&rsquo;Atletico et le Real Madrid a \u00e9t\u00e9 arr\u00eat\u00e9 pendant environ une demi-heure apr\u00e8s que des supporters du stade Wanda Metropolitano ont lanc\u00e9 des briquets et [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":26712,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfio_featured_image":false,"sfio_embed_code":"","footnotes":""},"categories":[220,222],"tags":[],"class_list":["post-26718","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-liga-fr","category-real-madrid-fr"],"_links":{"self":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/26718","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/comments?post=26718"}],"version-history":[{"count":1,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/26718\/revisions"}],"predecessor-version":[{"id":26719,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/26718\/revisions\/26719"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/media\/26712"}],"wp:attachment":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/media?parent=26718"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/categories?post=26718"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/tags?post=26718"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}