{"id":26263,"date":"2024-09-25T13:16:43","date_gmt":"2024-09-25T13:16:43","guid":{"rendered":"https:\/\/www.fanzword.com\/?p=26263"},"modified":"2024-09-25T13:16:43","modified_gmt":"2024-09-25T13:16:43","slug":"mbappe-sera-absent-pendant-une-periode-relativement-longue-en-raison-dune-blessure","status":"publish","type":"post","link":"https:\/\/www.fanzword.com\/fr\/mbappe-sera-absent-pendant-une-periode-relativement-longue-en-raison-dune-blessure\/","title":{"rendered":"Mbapp\u00e9 sera absent pendant une p\u00e9riode relativement longue en raison d&rsquo;une blessure"},"content":{"rendered":"<p>Le Real Madrid a r\u00e9v\u00e9l\u00e9 dans un communiqu\u00e9 officiel que Kylian Mbappe avait subi une blessure au biceps de la cuisse gauche.<\/p>\n<p>Mbapp\u00e9 a quitt\u00e9 le match contre Alaves mardi \u00e0 sa demande apr\u00e8s avoir ressenti une douleur \u00e0 la cuisse gauche.<\/p>\n<p>Mercredi soir, l&rsquo;international fran\u00e7ais a subi des examens approfondis au si\u00e8ge du Real Madrid \u00e0 Valdebebas, \u00e0 la suite desquels un communiqu\u00e9 du Real Madrid a \u00e9t\u00e9 publi\u00e9 annon\u00e7ant la nature de sa blessure, sans pr\u00e9ciser la dur\u00e9e de son absence.<\/p>\n<p>Comme l&rsquo;ont rapport\u00e9 plus tard les m\u00e9dias espagnols, Mbapp\u00e9 serait absent pendant au moins 3 semaines.<\/p>\n<p>Il est devenu certain que le joueur de 25 ans ne participera pas au derby madril\u00e8ne contre l&rsquo;Atletico Madrid, pr\u00e9vu la semaine prochaine au stade Wanda Metropolitano.<\/p>\n<p>L&rsquo;absence de Mbappe du Real Madrid lors des matches de Lille et Villarreal a \u00e9galement \u00e9t\u00e9 confirm\u00e9e, en plus de sa non-participation avec l&rsquo;\u00e9quipe de France \u00e0 la prochaine tr\u00eave internationale.<\/p>\n<p>Mbappe fera tout ce qu&rsquo;il peut pour revenir apr\u00e8s avoir arr\u00eat\u00e9 le match du Celta Vigo pr\u00e9vu le 19 octobre afin de terminer sa pr\u00e9paration pour le Cl\u00e1sico, qui aura lieu la semaine suivante au Santiago Bernabeu.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Real Madrid a r\u00e9v\u00e9l\u00e9 dans un communiqu\u00e9 officiel que Kylian Mbappe avait subi une blessure au biceps de la cuisse gauche. Mbapp\u00e9 a quitt\u00e9 le match contre Alaves mardi \u00e0 sa demande apr\u00e8s avoir ressenti une douleur \u00e0 la cuisse gauche. Mercredi soir, l&rsquo;international fran\u00e7ais a subi des examens approfondis au si\u00e8ge du Real [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":26259,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfio_featured_image":false,"sfio_embed_code":"","footnotes":""},"categories":[220,222],"tags":[],"class_list":["post-26263","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-liga-fr","category-real-madrid-fr"],"_links":{"self":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/26263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/comments?post=26263"}],"version-history":[{"count":1,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/26263\/revisions"}],"predecessor-version":[{"id":26264,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/26263\/revisions\/26264"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/media\/26259"}],"wp:attachment":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/media?parent=26263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/categories?post=26263"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/tags?post=26263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}