{"id":26216,"date":"2024-09-25T10:31:06","date_gmt":"2024-09-25T10:31:06","guid":{"rendered":"https:\/\/www.fanzword.com\/?p=26216"},"modified":"2024-09-25T10:31:06","modified_gmt":"2024-09-25T10:31:06","slug":"entraineur-dalaves-larbitre-est-la-raison-de-la-victoire-du-real-madrid","status":"publish","type":"post","link":"https:\/\/www.fanzword.com\/fr\/entraineur-dalaves-larbitre-est-la-raison-de-la-victoire-du-real-madrid\/","title":{"rendered":"Entra\u00eeneur d&rsquo;Alav\u00e9s : L&rsquo;arbitre est la raison de la victoire du Real Madrid !"},"content":{"rendered":"<p>L&rsquo;entra\u00eeneur d&rsquo;Alav\u00e9s, Luis Garcia Plaza, a lanc\u00e9 une attaque f\u00e9roce contre l&rsquo;arbitre du match de son \u00e9quipe contre le Real Madrid et l&rsquo;a consid\u00e9r\u00e9 comme l&rsquo;une des raisons de la victoire 3-2 du Royal Club, mardi en Liga.<\/p>\n<p>Garcia et les joueurs d&rsquo;Alav\u00e9s ont exig\u00e9 que le Br\u00e9silien Andric re\u00e7oive un carton rouge apr\u00e8s un tir au cours duquel il a frapp\u00e9 violemment le d\u00e9fenseur adverse, mais l&rsquo;arbitre s&rsquo;est content\u00e9 de donner un carton jaune au joueur.<\/p>\n<p>Apr\u00e8s le match, Garcia a parl\u00e9 \u00e0 Carlo Ancelotti et a exprim\u00e9 sa grande col\u00e8re face \u00e0 ce qui s&rsquo;est pass\u00e9, puis il s&rsquo;est adress\u00e9 \u00e0 la presse et a r\u00e9p\u00e9t\u00e9 la m\u00eame chose.<\/p>\n<p>\u00c0 cet \u00e9gard, Plaza a d\u00e9clar\u00e9 : \u00ab\u00a0L&rsquo;\u00e9tat d&rsquo;Indrik m\u00e9ritait un carton rouge et nous aurions d\u00fb jouer les 10 derni\u00e8res minutes avec un joueur suppl\u00e9mentaire\u00a0\u00bb.<\/p>\n<p>Il a \u00e9galement ajout\u00e9 : \u00ab\u00a0L&rsquo;intention d&rsquo;Indrek \u00e9tait clairement de nuire. Il m\u00e9rite incontestablement d&rsquo;\u00eatre expuls\u00e9 et rien d&rsquo;autre.\u00a0\u00bb<\/p>\n<p>Il a conclu : \u00ab\u00a0Le comportement d&rsquo;Indrik est clair pour tout le monde et tout le monde l&rsquo;a vu. C&rsquo;est un carton rouge clair et je ne comprends pas vraiment la d\u00e9cision de l&rsquo;arbitre.\u00a0\u00bb<\/p>\n<p>Si Indrik avait \u00e9t\u00e9 expuls\u00e9, Alaves aurait abord\u00e9 les derni\u00e8res minutes avec un avantage num\u00e9rique, augmentant ainsi ses chances d&rsquo;\u00e9galiser et de prendre un point devant le Santiago Bernabeu.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;entra\u00eeneur d&rsquo;Alav\u00e9s, Luis Garcia Plaza, a lanc\u00e9 une attaque f\u00e9roce contre l&rsquo;arbitre du match de son \u00e9quipe contre le Real Madrid et l&rsquo;a consid\u00e9r\u00e9 comme l&rsquo;une des raisons de la victoire 3-2 du Royal Club, mardi en Liga. Garcia et les joueurs d&rsquo;Alav\u00e9s ont exig\u00e9 que le Br\u00e9silien Andric re\u00e7oive un carton rouge apr\u00e8s un [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":26212,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfio_featured_image":false,"sfio_embed_code":"","footnotes":""},"categories":[220,222],"tags":[],"class_list":["post-26216","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-liga-fr","category-real-madrid-fr"],"_links":{"self":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/26216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/comments?post=26216"}],"version-history":[{"count":1,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/26216\/revisions"}],"predecessor-version":[{"id":26217,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/26216\/revisions\/26217"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/media\/26212"}],"wp:attachment":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/media?parent=26216"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/categories?post=26216"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/tags?post=26216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}