{"id":26170,"date":"2024-09-24T11:22:25","date_gmt":"2024-09-24T11:22:25","guid":{"rendered":"https:\/\/www.fanzword.com\/?p=26170"},"modified":"2024-09-24T11:22:25","modified_gmt":"2024-09-24T11:22:25","slug":"un-celebre-gardien-accepte-de-sortir-de-sa-retraite-aux-yeux-de-barcelone","status":"publish","type":"post","link":"https:\/\/www.fanzword.com\/fr\/un-celebre-gardien-accepte-de-sortir-de-sa-retraite-aux-yeux-de-barcelone\/","title":{"rendered":"Un c\u00e9l\u00e8bre gardien accepte de sortir de sa retraite aux yeux de Barcelone !"},"content":{"rendered":"<p>Le journal \u00ab\u00a0Sport\u00a0\u00bb a rapport\u00e9 que l&rsquo;ancien gardien de la Juventus, Szczesny, est pr\u00eat \u00e0 retourner sur les terrains de football pour porter le maillot de Barcelone.<\/p>\n<p>Szczesny avait annonc\u00e9 sa retraite apr\u00e8s l&rsquo;expiration de son contrat avec la Juventus la saison derni\u00e8re et l&rsquo;\u00e9chec des n\u00e9gociations pour rejoindre la Ligue saoudienne.<\/p>\n<p>\u00ab\u00a0Sport\u00a0\u00bb, citant les m\u00e9dias polonais, indique que Szczesny se r\u00e9jouit de revenir sur sa d\u00e9cision de prendre sa retraite afin de jouer une saison avec Barcelone.<\/p>\n<p>Le club catalan est \u00e0 la recherche d&rsquo;un nouveau gardien apr\u00e8s la blessure de Ter Stegen et son absence confirm\u00e9e pour la fin de la saison, et il n&rsquo;y a que le jeune gardien I\u00f1aki Pe\u00f1a.<\/p>\n<p>Barcelone peut inclure un gardien et l&rsquo;ajouter \u00e0 sa liste \u00e0 la place de Ter Stegen au plus tard le 22 octobre, mais attendre janvier signifiera la possibilit\u00e9 qu&rsquo;il ne soit pas inscrit en raison des r\u00e8gles du fair-play financier.<\/p>\n<p>Le nom de Szczesny est apparu avec de nombreux autres noms, men\u00e9s par l&rsquo;ancien gardien du Real Madrid Keylor Navas, comme options sur la table de la direction de Joan Laporta pour remplacer Stegen.<\/p>\n<p>D\u2019un point de vue pratique, Szczesny semble \u00eatre le choix le plus judicieux parmi tous les noms propos\u00e9s, puisqu\u2019il a jou\u00e9 pour deux des \u00e9quipes d\u2019\u00e9lite europ\u00e9ennes, Arsenal et Juventus, en plus de sa vaste exp\u00e9rience avec l\u2019\u00e9quipe nationale polonaise.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le journal \u00ab\u00a0Sport\u00a0\u00bb a rapport\u00e9 que l&rsquo;ancien gardien de la Juventus, Szczesny, est pr\u00eat \u00e0 retourner sur les terrains de football pour porter le maillot de Barcelone. Szczesny avait annonc\u00e9 sa retraite apr\u00e8s l&rsquo;expiration de son contrat avec la Juventus la saison derni\u00e8re et l&rsquo;\u00e9chec des n\u00e9gociations pour rejoindre la Ligue saoudienne. \u00ab\u00a0Sport\u00a0\u00bb, citant les [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":26166,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfio_featured_image":false,"sfio_embed_code":"","footnotes":""},"categories":[221,220],"tags":[],"class_list":["post-26170","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-barcelona-fr","category-la-liga-fr"],"_links":{"self":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/26170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/comments?post=26170"}],"version-history":[{"count":1,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/26170\/revisions"}],"predecessor-version":[{"id":26171,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/26170\/revisions\/26171"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/media\/26166"}],"wp:attachment":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/media?parent=26170"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/categories?post=26170"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/tags?post=26170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}