{"id":20563,"date":"2024-07-24T10:50:19","date_gmt":"2024-07-24T10:50:19","guid":{"rendered":"https:\/\/www.fanzword.com\/?p=20563"},"modified":"2024-07-24T10:50:19","modified_gmt":"2024-07-24T10:50:19","slug":"guardiola-confirme-quun-star-de-manchester-city-est-proche-de-rejoindre-la-ligue-saoudienne","status":"publish","type":"post","link":"https:\/\/www.fanzword.com\/fr\/guardiola-confirme-quun-star-de-manchester-city-est-proche-de-rejoindre-la-ligue-saoudienne\/","title":{"rendered":"Guardiola confirme qu&rsquo;un star de Manchester City est proche de rejoindre la ligue saoudienne"},"content":{"rendered":"<div class=\"presented-response-container ng-tns-c1222400322-34\">\n<div class=\"response-container-content ng-tns-c1222400322-34\">\n<div class=\"response-content ng-tns-c1222400322-34\">\n<div class=\"markdown markdown-main-panel\" dir=\"ltr\">\n<p data-sourcepos=\"21:1-21:162\">L&rsquo;entra\u00eeneur de Manchester City, Pep Guardiola, a laiss\u00e9 entendre la possibilit\u00e9 qu&rsquo;Ederson rejoigne le club saoudien Al-Ittihad lors du mercato estival en cours.<\/p>\n<p data-sourcepos=\"23:1-23:203\">Ederson \u00e9tait sur le point de rejoindre Al-Nassr ces derni\u00e8res semaines, mais Al-Nassr n&rsquo;a pas r\u00e9ussi \u00e0 trouver un accord avec Manchester City en raison des exigences financi\u00e8res \u00e9lev\u00e9es du club anglais.<\/p>\n<p data-sourcepos=\"25:1-25:181\">Les n\u00e9gociations entre Ederson et Al-Ittihad sont d\u00e9sormais \u00e0 un stade tr\u00e8s avanc\u00e9, et Guardiola confirme dans sa d\u00e9claration qu&rsquo;il ne s&rsquo;opposera pas au d\u00e9part du gardien br\u00e9silien.<\/p>\n<p data-sourcepos=\"27:1-27:140\">Lorsqu&rsquo;il a \u00e9t\u00e9 interrog\u00e9 sur l&rsquo;avenir d&rsquo;Ederson apr\u00e8s le match amical contre le Celtic, l&rsquo;entra\u00eeneur espagnol a r\u00e9pondu : \u00ab\u00a0Je ne sais pas.\u00a0\u00bb<\/p>\n<p data-sourcepos=\"29:1-29:144\">Il a \u00e9galement ajout\u00e9, laissant entendre que la porte est ouverte au d\u00e9part du gardien de but : \u00ab\u00a0C&rsquo;est \u00e0 lui de prendre la d\u00e9cision, pas \u00e0 moi.\u00a0\u00bb<\/p>\n<p data-sourcepos=\"31:1-31:103\">Il convient de noter que Manchester City exige entre 50 et 60 millions d&rsquo;euros pour la vente d&rsquo;Ederson.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;entra\u00eeneur de Manchester City, Pep Guardiola, a laiss\u00e9 entendre la possibilit\u00e9 qu&rsquo;Ederson rejoigne le club saoudien Al-Ittihad lors du mercato estival en cours. Ederson \u00e9tait sur le point de rejoindre Al-Nassr ces derni\u00e8res semaines, mais Al-Nassr n&rsquo;a pas r\u00e9ussi \u00e0 trouver un accord avec Manchester City en raison des exigences financi\u00e8res \u00e9lev\u00e9es du club anglais. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":20559,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfio_featured_image":false,"sfio_embed_code":"","footnotes":""},"categories":[210,212,223,233],"tags":[],"class_list":["post-20563","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ittihad","category-premier-league","category-saudi-pro-league-fr","category-transferts"],"_links":{"self":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/20563","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/comments?post=20563"}],"version-history":[{"count":1,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/20563\/revisions"}],"predecessor-version":[{"id":20564,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/20563\/revisions\/20564"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/media\/20559"}],"wp:attachment":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/media?parent=20563"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/categories?post=20563"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/tags?post=20563"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}