{"id":20386,"date":"2024-07-22T10:04:20","date_gmt":"2024-07-22T10:04:20","guid":{"rendered":"https:\/\/www.fanzword.com\/?p=20386"},"modified":"2024-07-22T10:04:20","modified_gmt":"2024-07-22T10:04:20","slug":"un-club-saoudien-recrute-une-star-de-la-premier-league-pour-60-millions-deuros","status":"publish","type":"post","link":"https:\/\/www.fanzword.com\/fr\/un-club-saoudien-recrute-une-star-de-la-premier-league-pour-60-millions-deuros\/","title":{"rendered":"Un club saoudien recrute une star de la Premier League pour 60 millions d&rsquo;euros"},"content":{"rendered":"<p data-sourcepos=\"23:1-23:216\">Les m\u00e9dias internationaux ont confirm\u00e9 que la direction d&rsquo;Al-Ittihad a r\u00e9ussi \u00e0 conclure un contrat avec la star d&rsquo;Aston Villa, Moussa Dembele, et que l&rsquo;accord devrait \u00eatre officialis\u00e9 dans les prochaines heures.<\/p>\n<p data-sourcepos=\"25:1-25:187\">Ce n&rsquo;est pas la premi\u00e8re fois qu&rsquo;Al-Ittihad s&rsquo;int\u00e9resse \u00e0 Dembele, puisque le joueur figurait sur la liste de souhaits du club l&rsquo;\u00e9t\u00e9 dernier avant de d\u00e9cider de rejoindre Aston Villa.<\/p>\n<p data-sourcepos=\"27:1-27:164\">Cependant, cette fois-ci, la direction du \u00ab\u00a0Dean\u00a0\u00bb a r\u00e9ussi \u00e0 trouver un accord avec le joueur et son club, et selon le journal Al-Riyadiah, le montant du transfert atteindra 60 millions d&rsquo;euros avec des variables et des compl\u00e9ments.<\/p>\n<p data-sourcepos=\"29:1-29:159\">Le joueur de 25 ans signera un contrat de longue dur\u00e9e qui le liera au club jaune jusqu&rsquo;\u00e0 l&rsquo;\u00e9t\u00e9 2029 avec un salaire annuel d&rsquo;au moins 20 millions d&rsquo;euros.<\/p>\n<p data-sourcepos=\"31:1-31:153\">L&rsquo;international fran\u00e7ais a disput\u00e9 38 matchs avec Aston Villa la saison derni\u00e8re, au cours desquels il a marqu\u00e9 6 buts et d\u00e9livr\u00e9 8 passes d\u00e9cisives.<\/p>\n<p data-sourcepos=\"33:1-33:216\">La signature de Dembele est la troisi\u00e8me \u00e9tape d&rsquo;Al-Ittihad sur le march\u00e9 des transferts estivaux apr\u00e8s avoir recrut\u00e9 l&rsquo;entra\u00eeneur fran\u00e7ais Laurent Blanc et la star alg\u00e9rienne Houssem Aouar en provenance de Rome.<\/p>\n<p data-sourcepos=\"35:1-35:173\">Et les d\u00e9marches estivales d&rsquo;Al-Ittihad ne devraient pas s&rsquo;arr\u00eater l\u00e0, puisque le club saoudien a \u00e9t\u00e9 li\u00e9 au recrutement du gardien br\u00e9silien Ederson de Manchester City.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les m\u00e9dias internationaux ont confirm\u00e9 que la direction d&rsquo;Al-Ittihad a r\u00e9ussi \u00e0 conclure un contrat avec la star d&rsquo;Aston Villa, Moussa Dembele, et que l&rsquo;accord devrait \u00eatre officialis\u00e9 dans les prochaines heures. Ce n&rsquo;est pas la premi\u00e8re fois qu&rsquo;Al-Ittihad s&rsquo;int\u00e9resse \u00e0 Dembele, puisque le joueur figurait sur la liste de souhaits du club l&rsquo;\u00e9t\u00e9 dernier [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":20380,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfio_featured_image":false,"sfio_embed_code":"","footnotes":""},"categories":[210,212,223,233],"tags":[],"class_list":["post-20386","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ittihad","category-premier-league","category-saudi-pro-league-fr","category-transferts"],"_links":{"self":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/20386","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/comments?post=20386"}],"version-history":[{"count":2,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/20386\/revisions"}],"predecessor-version":[{"id":20388,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/20386\/revisions\/20388"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/media\/20380"}],"wp:attachment":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/media?parent=20386"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/categories?post=20386"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/tags?post=20386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}