{"id":19827,"date":"2024-07-17T06:06:44","date_gmt":"2024-07-17T06:06:44","guid":{"rendered":"https:\/\/www.fanzword.com\/?p=19827"},"modified":"2024-07-17T06:06:44","modified_gmt":"2024-07-17T06:06:44","slug":"la-france-accuse-largentine-de-racisme-les-joueurs-de-chelsea-se-rebellent-contre-enzo","status":"publish","type":"post","link":"https:\/\/www.fanzword.com\/fr\/la-france-accuse-largentine-de-racisme-les-joueurs-de-chelsea-se-rebellent-contre-enzo\/","title":{"rendered":"La France accuse l&rsquo;Argentine de racisme, les joueurs de Chelsea se rebellent contre Enzo"},"content":{"rendered":"<p data-sourcepos=\"23:1-23:419\">La star de Chelsea et de l&rsquo;\u00e9quipe nationale argentine, Enzo Fernandez, a diffus\u00e9 en direct une vid\u00e9o sur son compte Instagram avec ses co\u00e9quipiers de l&rsquo;\u00e9quipe nationale c\u00e9l\u00e9brant leur titre de Copa America 2024 depuis l&rsquo;int\u00e9rieur du bus de l&rsquo;\u00e9quipe. Cette vid\u00e9o a d\u00e9clench\u00e9 une controverse majeure car elle comprenait des propos racistes de la part des joueurs argentins envers des joueurs fran\u00e7ais d&rsquo;origine africaine.<\/p>\n<p data-sourcepos=\"25:1-25:172\">La F\u00e9d\u00e9ration fran\u00e7aise de football (FFF) a d\u00e9pos\u00e9 une plainte officielle contre les joueurs argentins aupr\u00e8s de la FIFA pour cette vid\u00e9o. Cependant, l&rsquo;affaire ne s&rsquo;est pas arr\u00eat\u00e9e au niveau national, mais a \u00e9galement provoqu\u00e9 des remous au sein des clubs.<\/p>\n<p data-sourcepos=\"27:1-27:209\">Selon les journaux anglais, les joueurs fran\u00e7ais de Chelsea sont furieux contre Fernandez, au point que Wesley Fofana, Malo Gusto et Axel Disasi ont cess\u00e9 de suivre le joueur argentin sur les r\u00e9seaux sociaux.<\/p>\n<p data-sourcepos=\"29:1-29:88\">Fofana a comment\u00e9 la vid\u00e9o sur son compte et \u00e9crit \u00ab\u00a0Football 2024 : Racisme sans frein\u00a0\u00bb.<\/p>\n<p data-sourcepos=\"31:1-31:239\">De son c\u00f4t\u00e9, Chelsea a d\u00e9cid\u00e9 d&rsquo;ouvrir une enqu\u00eate urgente sur ce qui s&rsquo;est pass\u00e9, ce qui pourrait aboutir \u00e0 la suspension de Fernandez. Certains ont m\u00eame pr\u00e9dit que cela pourrait \u00eatre la fin de la carri\u00e8re de l&rsquo;Argentin \u00e0 Stamford Bridge.<\/p>\n<p data-sourcepos=\"33:1-33:209\">Fernandez, quant \u00e0 lui, a publi\u00e9 une d\u00e9claration dans laquelle il s&rsquo;excuse pour ce qui s&rsquo;est pass\u00e9, en disant \u00ab\u00a0La chanson contient un langage violent et il n&rsquo;y a vraiment aucune excuse pour utiliser ces mots\u00a0\u00bb.<\/p>\n<p data-sourcepos=\"35:1-35:153\">Il a ajout\u00e9 : \u00ab\u00a0Je suis vraiment d\u00e9sol\u00e9, je suis contre toute forme de discrimination. Cette vid\u00e9o et ces mots ne refl\u00e8tent pas vraiment ma personnalit\u00e9.\u00a0\u00bb<\/p>\n<p data-sourcepos=\"37:1-37:155\">Il est \u00e0 noter que Lionel Messi n&rsquo;\u00e9tait pas pr\u00e9sent dans le bus lors des chants, pas plus que d&rsquo;autres stars comme Emiliano Martinez et Alexis Mac Allister<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La star de Chelsea et de l&rsquo;\u00e9quipe nationale argentine, Enzo Fernandez, a diffus\u00e9 en direct une vid\u00e9o sur son compte Instagram avec ses co\u00e9quipiers de l&rsquo;\u00e9quipe nationale c\u00e9l\u00e9brant leur titre de Copa America 2024 depuis l&rsquo;int\u00e9rieur du bus de l&rsquo;\u00e9quipe. Cette vid\u00e9o a d\u00e9clench\u00e9 une controverse majeure car elle comprenait des propos racistes de la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":19822,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfio_featured_image":false,"sfio_embed_code":"","footnotes":""},"categories":[212],"tags":[],"class_list":["post-19827","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-premier-league"],"_links":{"self":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/19827","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/comments?post=19827"}],"version-history":[{"count":1,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/19827\/revisions"}],"predecessor-version":[{"id":19828,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/posts\/19827\/revisions\/19828"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/media\/19822"}],"wp:attachment":[{"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/media?parent=19827"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/categories?post=19827"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fanzword.com\/fr\/wp-json\/wp\/v2\/tags?post=19827"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}